{"id":19993,"date":"2022-07-06T13:02:55","date_gmt":"2022-07-06T11:02:55","guid":{"rendered":"https:\/\/suport.fundesplai.org\/?p=19993"},"modified":"2022-07-20T08:48:42","modified_gmt":"2022-07-20T06:48:42","slug":"deutes-agencia-tributaria","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/","title":{"rendered":"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA?"},"content":{"rendered":"<p>Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable.<\/p>\n<p>Independientemente de si es la \u00e9poca de la <strong>declaraci\u00f3n de la renta<\/strong> o no, es importante que todas las personas y entidades est\u00e9n seguras que no tienen ninguna deuda con la <a href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/inicio.html\" target=\"_blank\" rel=\"noopener\">Agencia Tributaria<\/a>. En caso de que la persona u organizaci\u00f3n tenga cuentas pendientes puede encontrarse con una serie de consecuencias negativas:<\/p>\n<ul>\n<li>Tener <strong>bloqueados pagos pendientes<\/strong> por parte de Hacienda.<\/li>\n<li>Obtener <strong>negativas<\/strong> cuando se pide una <strong>hipoteca<\/strong>, <strong>pr\u00e9stamo<\/strong> o alg\u00fan tipo de <strong>financiaci\u00f3n bancaria<\/strong>.<\/li>\n<li>Situaci\u00f3n en la cual una persona asalariada, proveedor\/a o tercero reciba una <strong>diligencia de embargos de cr\u00e9ditos<\/strong>.<\/li>\n<li>Que la <strong>n\u00f3mina<\/strong> o la <strong>cuenta bancaria<\/strong> de la persona o entidad con deuda est\u00e9 <strong>embargada<\/strong>.<\/li>\n<\/ul>\n<pre><\/pre>\n<div class=\"views-field views-field-field-subtitols\">\n<div id=\"rec1\">\n<h3>\u00bfC\u00d3MO DESCUBRIR SI SE TIENEN DEUDAS CON HACIENDA?<\/h3>\n<\/div>\n<\/div>\n<div class=\"views-field views-field-field-continguts\">\n<div class=\"field-content\">\n<p>Para comprobar si se tienen deudas con Hacienda hay dos maneras, virtualmente o presencialmente. Si se escoge hacer la consulta en l\u00ednea, se puede realizar de forma r\u00e1pida e inmediata. En la web de la <strong>Agencia Tributaria<\/strong> se tiene que acceder a la secci\u00f3n \u2018<a href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/deudas-apremios-embargos-subastas\/pagar-aplazar-consultar.html\" target=\"_blank\" rel=\"noopener\">Consultar deudas<\/a>\u2019, una vez dentro se tiene que introducir el <a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/actualidad\/como-obtener-el-certificado-digital-de-una-entidad-religiosa\/\" target=\"_blank\" rel=\"noopener\">certificado electr\u00f3nico<\/a>, el <strong>DNI electr\u00f3nico<\/strong> o la <strong>Cl@ve PIN<\/strong>. Cuando se realiza la consulta se puede observar: la <strong>clave de liquidaci\u00f3n<\/strong>, el objeto tributario, el importe total y pendiente, el periodo y la situaci\u00f3n en la cual se encuentra la deuda en este momento. Pulsando sobre la clave de liquidaci\u00f3n de una deuda se puede acceder al por menor de la deuda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19968\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-800x215.png\" alt=\"\" width=\"800\" height=\"215\" srcset=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-800x215.png 800w, https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-480x129.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19972\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/2-800x580.png\" alt=\"\" width=\"800\" height=\"580\" srcset=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/2-800x580.png 800w, https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/2-480x348.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<p>Si se necesita m\u00e1s informaci\u00f3n, se tienen dudas sobre la situaci\u00f3n de las deudas y\/o no se tienen los datos de acceso, se tiene que pedir una cita presencial. Para poder concertar una reuni\u00f3n hay que <a href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/procedimientoini\/GC29.shtml\" target=\"_blank\" rel=\"noopener\">pedir cita previa<\/a>.<\/p>\n<pre><\/pre>\n<h3>\u00bfQU\u00c9 HACER SI SE DESCUBRE QUE SE TIENEN DEUDAS?<\/h3>\n<p>En caso de descubrir que se tienen cuentas pendientes con Hacienda se puede <strong>proceder al pago<\/strong> pertinente o bien presentar una <a href=\"https:\/\/sede.agenciatributaria.gob.es\/Sede\/deudas-apremios-embargos-subastas\/pagar-aplazar-consultar.html\" target=\"_blank\" rel=\"noopener\">solicitud de aplazamiento o de fraccionamiento<\/a> de la cuant\u00eda que se debe. Si se escoge la primera opci\u00f3n, se tendr\u00e1 que continuar con el tr\u00e1mite y se clicar\u00e1 sobre \u2018<strong>obtener carta de pago<\/strong>\u2018 para proceder al ingreso.<\/p>\n<div class=\"views-field views-field-field-continguts\">\n<div class=\"field-content\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19970\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/2-reducido-800x145.png\" alt=\"\" width=\"800\" height=\"145\" srcset=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/2-reducido-800x145.png 800w, https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/2-reducido-480x87.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<p>En cambio, si se necesita <strong>aplazar <\/strong>o<strong> fraccionar<\/strong> lo que se debe se tiene que <strong>presentar una solicitud<\/strong> que tendr\u00e1 que aceptar Hacienda. Ser\u00e1n v\u00e1lidas solo aquellas solicitudes donde las deudas est\u00e9n en periodo voluntario o ejecutivo y se pueda acreditar que la persona u organizaci\u00f3n tiene una situaci\u00f3n econ\u00f3mico-financiera que le impida, de forma transitoria, llevar a cabo el pago.<\/p>\n<pre><\/pre>\n<h3>\u00bfC\u00d3MO SE PUEDE PROCEDER AL PAGO DE LAS CUENTAS PENDIENTES?<\/h3>\n<div class=\"views-field views-field-field-continguts\">\n<div class=\"field-content\">\n<p>Para poder <strong>efectuar el pago<\/strong> pendiente con Hacienda es necesario continuar con el tr\u00e1mite. Una vez se ha pedido la<strong> carta de pago<\/strong> saldr\u00e1n los datos de la persona en cuesti\u00f3n, y si todo est\u00e1 correcto se tiene que clicar a \u2018Aceptar\u2019.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-19974 size-medium\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/3-800x621.png\" alt=\"\" width=\"800\" height=\"621\" srcset=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/3-800x621.png 800w, https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/3-480x373.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<div class=\"views-row views-row-3 views-row-odd\">\n<div class=\"views-field views-field-field-continguts\">\n<div class=\"field-content\">\n<p>En la siguiente p\u00e1gina se puede seleccionar el m\u00e9todo de pago que se desea: una opci\u00f3n es obtener el \u2018<strong>documento de ingreso<\/strong>\u2018 para poder hacer el pago en una entidad bancaria. Otra opci\u00f3n es llevar a cabo el pago de forma virtual e inmediata. El pago mediante deuda en cuenta est\u00e1 disponible con el certificado digital, el DNI electr\u00f3nico o la Cl@ve PIN. En cambio, el pago mediante tarjeta de cr\u00e9dito o d\u00e9bito solo est\u00e1 habilitado con el certificado digital o el DNI electr\u00f3nico.<\/p>\n<pre><\/pre>\n<h3>\u00bfQU\u00c9 PASA SI HAY M\u00c1S DE UNA DEUDA PARA PAGAR?<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"views-row views-row-4 views-row-even views-row-last\">\n<div class=\"views-field views-field-field-continguts\">\n<div class=\"field-content\">\n<p>Cuando se tienen m\u00e1s de una deuda pendiente con la Agencia Tributaria existe la posibilidad de generar una misma carta de pago. En caso de que no sea posible se tendr\u00e1 que generar de forma individual. A las im\u00e1genes que se encuentran a continuaci\u00f3n se puede ver como se dividen las deudas entre los cuales se pueden pagar de forma individual y los que hay la opci\u00f3n de efectuar el <strong>pago de forma conjunta<\/strong>, en este caso se tendr\u00e1 que seleccionar aquellas deudas que se quieran pagar a la vez.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19976\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/4-800x374.png\" alt=\"\" width=\"800\" height=\"374\" srcset=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/4-800x374.png 800w, https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/4-480x224.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-19978\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/5-800x467.png\" alt=\"\" width=\"800\" height=\"467\" srcset=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/5-800x467.png 800w, https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/5-480x280.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/p>\n<p>Fuente: <a href=\"https:\/\/xarxanet.org\/economic\/recursos\/com-saber-si-es-te-deutes-amb-lagencia-tributaria\" target=\"_blank\" rel=\"noopener\">Xarxanet<\/a>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable. Independientemente de si es la \u00e9poca de la declaraci\u00f3n de la renta o no, es importante que todas las personas y entidades est\u00e9n seguras que no tienen ninguna deuda con la Agencia Tributaria. En caso de que la persona u [&hellip;]<\/p>\n","protected":false},"author":377,"featured_media":19980,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[341,285],"tags":[673,679,674,715,722,723,716,605,717,724],"class_list":["post-19993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-economico","tag-agencia-tributaria-es","tag-certificado-digital","tag-certificat-digital-es","tag-declaracio-de-la-renda-es","tag-declaracion-de-la-renta","tag-deuda","tag-deute-es","tag-fiscalidad","tag-transparencia-i-rendicio-de-comptes-es","tag-transparencia-y-rendimiento-de-cuentas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA? - Suport Tercer Sector - Fundesplai<\/title>\n<meta name=\"description\" content=\"Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA? - Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T11:02:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-20T06:48:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-1-e1657098398744.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maria Eugenia Ifer Puntigliano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Eugenia Ifer Puntigliano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/\"},\"author\":{\"name\":\"Maria Eugenia Ifer Puntigliano\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/d67e880480b45b41df0ab5d2c3670fba\"},\"headline\":\"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA?\",\"datePublished\":\"2022-07-06T11:02:55+00:00\",\"dateModified\":\"2022-07-20T06:48:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/\"},\"wordCount\":715,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1-1-e1657098398744.png\",\"keywords\":[\"ag\u00e8ncia tribut\u00e0ria\",\"certificado digital\",\"certificat digital\",\"declaraci\u00f3 de la renda\",\"declaraci\u00f3n de la renta\",\"deuda\",\"deute\",\"fiscalidad\",\"transpar\u00e8ncia i rendici\u00f3 de comptes\",\"transparencia y rendimiento de cuentas\"],\"articleSection\":[\"Blog\",\"Econ\u00f3mico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/\",\"name\":\"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA? - Suport Tercer Sector - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1-1-e1657098398744.png\",\"datePublished\":\"2022-07-06T11:02:55+00:00\",\"dateModified\":\"2022-07-20T06:48:42+00:00\",\"description\":\"Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1-1-e1657098398744.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/1-1-e1657098398744.png\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/deutes-agencia-tributaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/d67e880480b45b41df0ab5d2c3670fba\",\"name\":\"Maria Eugenia Ifer Puntigliano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g\",\"caption\":\"Maria Eugenia Ifer Puntigliano\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/meifer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA? - Suport Tercer Sector - Fundesplai","description":"Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA? - Suport Tercer Sector - Fundesplai","og_description":"Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2022-07-06T11:02:55+00:00","article_modified_time":"2022-07-20T06:48:42+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-1-e1657098398744.png","type":"image\/png"}],"author":"Maria Eugenia Ifer Puntigliano","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"Maria Eugenia Ifer Puntigliano","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/"},"author":{"name":"Maria Eugenia Ifer Puntigliano","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/d67e880480b45b41df0ab5d2c3670fba"},"headline":"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA?","datePublished":"2022-07-06T11:02:55+00:00","dateModified":"2022-07-20T06:48:42+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/"},"wordCount":715,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-1-e1657098398744.png","keywords":["ag\u00e8ncia tribut\u00e0ria","certificado digital","certificat digital","declaraci\u00f3 de la renda","declaraci\u00f3n de la renta","deuda","deute","fiscalidad","transpar\u00e8ncia i rendici\u00f3 de comptes","transparencia y rendimiento de cuentas"],"articleSection":["Blog","Econ\u00f3mico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/","name":"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA? - Suport Tercer Sector - Fundesplai","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-1-e1657098398744.png","datePublished":"2022-07-06T11:02:55+00:00","dateModified":"2022-07-20T06:48:42+00:00","description":"Asegurarse que no se tienen cuentas pendientes con hacienda ayuda a garantizar una econom\u00eda estable.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-1-e1657098398744.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/07\/1-1-e1657098398744.png","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/deutes-agencia-tributaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"\u00bfC\u00d3MO SABER SI SE TIENEN DEUDAS CON LA AGENCIA TRIBUTARIA?"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/d67e880480b45b41df0ab5d2c3670fba","name":"Maria Eugenia Ifer Puntigliano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g","caption":"Maria Eugenia Ifer Puntigliano"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/meifer\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/19993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=19993"}],"version-history":[{"count":8,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/19993\/revisions"}],"predecessor-version":[{"id":20077,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/19993\/revisions\/20077"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/19980"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=19993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=19993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=19993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}