{"id":20150,"date":"2022-08-24T12:53:44","date_gmt":"2022-08-24T10:53:44","guid":{"rendered":"https:\/\/suport.fundesplai.org\/blog-es\/actualidad\/todo-lo-que-debes-saber-sobre-el-nuevo-registro-de-entidades-de-medio-ambiente\/"},"modified":"2022-08-24T13:21:10","modified_gmt":"2022-08-24T11:21:10","slug":"lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/","title":{"rendered":"Todo lo que debes saber sobre el nuevo Registro de Entidades de Medio Ambiente"},"content":{"rendered":"<h2 style=\"font-size: 18px;\">Si tu organizaci\u00f3n ya trabaja por el medio ambiente, se puede inscribir en el Registro de Entidades de Medio Ambiente, impulsado por la Secretar\u00eda de Acci\u00f3n Clim\u00e1tica de la Generalitat.<\/h2>\n<p>Desde principios de 2022 hay un nuevo registro en el que se pueden inscribir las entidades no lucrativas que trabajan por la <strong>protecci\u00f3n del medio ambiente.<\/strong> Se trata del <a href=\"https:\/\/mediambient.gencat.cat\/es\/05_ambits_dactuacio\/educacio_i_sostenibilitat\/tercer_sector_ambiental\/registre_dentitats\/index.html\">Registro de Entidades de Medio Ambiente<\/a>, creado a partir del <a href=\"https:\/\/portaldogc.gencat.cat\/utilsEADOP\/PDF\/8579\/1885769.pdf\">Decreto 2\/2022<\/a>. De este modo, las entidades registradas pueden acceder a <strong>convocatorias de subvenciones<\/strong> de una manera m\u00e1s f\u00e1cil, pasan a considerarse como interesadas en referencia al medio ambiente (con lo cual pueden recibir informaci\u00f3n al respeto) y obtienen <strong>beneficios fiscales.<\/strong><\/p>\n<h3>Mi entidad ya estaba inscrita en el antiguo registro<\/h3>\n<p>La nueva normativa comporta la<strong> derogaci\u00f3n del Decreto 401\/2004,<\/strong> de 5 de octubre, vigente hasta principios de 2022. El <strong>cambio del antiguo registro<\/strong> al nuevo se ha hecho autom\u00e1ticamente. Esto significa que, si no se ha recibido ninguna notificaci\u00f3n indicando el no cumplimiento de los requisitos, no hay que hacer ning\u00fan cambio.<\/p>\n<p>En cualquier caso, las entidades que han pasado de un registro al otro tambi\u00e9n deben haber recibido una notificaci\u00f3n sobre el procedimiento aplicado.<\/p>\n<p>El objetivo de la creaci\u00f3n del nuevo registro es \u201csimplificar el ejercicio de los intereses leg\u00edtimos colectivos de car\u00e1cter ambiental de las entidades inscritas\u201d.<\/p>\n<h3>Qui\u00e9n puede inscribirse en el Registro de Entidades de Medio Ambiente<\/h3>\n<p>Se pueden registrar entidades sin \u00e1nimo de lucro que trabajen por la <strong>protecci\u00f3n del medio ambiente<\/strong>, que est\u00e9n constituidas legalmente y que tengan la sede o una delegaci\u00f3n en el territorio catal\u00e1n o que ejerzan su actividad en el mismo.<\/p>\n<p>Esta finalidad tiene que <strong>aparecer en sus estatutos<\/strong> y se puede llevar a cabo de forma general o a trav\u00e9s de alg\u00fan elemento en particular. Adem\u00e1s, es necesario que estas actividades se desarrollen durante <strong>dos a\u00f1os consecutivos<\/strong> anteriores a la solicitud de inscripci\u00f3n.<\/p>\n<p>Hay que tener en cuenta que<strong> no se pueden inscribir<\/strong> en el Registro de Entidades de Medio Ambiente las universidades, sindicatos, partidos pol\u00edticos, colegios profesionales ni asociaciones empresariales o profesionales.<\/p>\n<h3>C\u00f3mo inscribirse en el registro<\/h3>\n<p>Para registrarse hay que rellenar la<a href=\"https:\/\/ovt.gencat.cat\/gsitgf\/AppJava\/traint\/renderitzar.do?reqCode=inicial&amp;set-locale=es_ES&amp;idioma=&amp;idServei=DPA026INSC&amp;origen=CE\"> &#8216;Solicitud para la inscripci\u00f3n en el Registro de entidades de medio ambiente&#8217;<\/a>, validarla y firmarla. De este modo deja de ser un borrador y el documento queda bloqueado.<\/p>\n<p>La entidad no lucrativa tiene que incluir la <strong>memoria acreditativa de actividad<\/strong> enlazando a la p\u00e1gina web, a trav\u00e9s de otro canal electr\u00f3nico que permita su consulta o adjuntando un archivo.<\/p>\n<p>Una vez se haya rellenado el formulario, adjuntada la documentaci\u00f3n y guardada se tiene que enviar el archivo. Cuando esto se haya realizado, se recibir\u00e1 un acuse de recibo seg\u00fan se haya registrado el formulario. Este acuse permite a la entidad hacer un seguimiento del estado de la tramitaci\u00f3n, hacer los pagos o adjuntar informaci\u00f3n, si es necesario.<\/p>\n<p>La administraci\u00f3n dispone de un mes para publicar la resoluci\u00f3n a contar desde la presentaci\u00f3n de la solicitud. La notificaci\u00f3n se puede consultar en el correo electr\u00f3nico, en el apartado <a href=\"https:\/\/ovt.gencat.cat\/gsitfc\/AppJava\/nottel\/notificationPassKey.do?set-locale=es_ES&amp;reqCode=chooseAcces&amp;portalId=1\">\u2018Notificaciones electr\u00f3nicas\u2019<\/a>, en el<a href=\"https:\/\/ovt.gencat.cat\/gsitfc\/AppJava\/ce\/nottel\/notificationPassKeyCE.do?set-locale=es_ES&amp;reqCodeChangeLanguage=chooseAcces\"> Canal Empresa<\/a> o en el <a href=\"https:\/\/ovt.gencat.cat\/carpetaciutadana360#\/acces\">\u00e1rea privada de Tr\u00e1mites gencat<\/a>. Hay que acceder a la notificaci\u00f3n en los siguientes diez d\u00edas desde la recepci\u00f3n para aceptarla, puesto que en caso contrario se entender\u00e1 como rechazada.<\/p>\n<h3>Beneficios fiscales para las entidades inscritas<\/h3>\n<p>Ciertos tipos de donaciones se benefician de <a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/actualidad\/desgravacion-de-las-donaciones-a-asociaciones-y-fundaciones\/\">deducciones fiscales<\/a>. Estar inscritas en el Registro de Entidades de Medio Ambiente permite a las personas donantes <strong>desgravarse un 15% de la donaci\u00f3n<\/strong> en la cuota de la declaraci\u00f3n de la renta, con un l\u00edmite m\u00e1ximo del 5% de la cuota \u00edntegra auton\u00f3mica.<\/p>\n<p>Si tienes dudas o quieres saber m\u00e1s sobre este tema, ponte en <a href=\"https:\/\/suport.fundesplai.org\/es\/contacta\/\">contacto con nosotros<\/a> y resolveremos todas tus preguntas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si tu organizaci\u00f3n ya trabaja por el medio ambiente, se puede inscribir en el Registro de Entidades de Medio Ambiente, impulsado por la Secretar\u00eda de Acci\u00f3n Clim\u00e1tica de la Generalitat. Desde principios de 2022 hay un nuevo registro en el que se pueden inscribir las entidades no lucrativas que trabajan por la protecci\u00f3n del medio [&hellip;]<\/p>\n","protected":false},"author":360,"featured_media":20135,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,341,295,275],"tags":[],"class_list":["post-20150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-blog-es","category-fiscal-es","category-juridico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Registro de Entidades de Medio Ambiente<\/title>\n<meta name=\"description\" content=\"Las entidades no lucrativas que trabajen por el medio ambiente se pueden inscribir en el Registro de Entidades de Medio Ambiente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Registro de Entidades de Medio Ambiente\" \/>\n<meta property=\"og:description\" content=\"Las entidades no lucrativas que trabajen por el medio ambiente se pueden inscribir en el Registro de Entidades de Medio Ambiente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-24T10:53:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-24T11:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/08\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"spulido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"spulido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/\"},\"author\":{\"name\":\"spulido\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/fdf6420f515befcbe14be21cbe303807\"},\"headline\":\"Todo lo que debes saber sobre el nuevo Registro de Entidades de Medio Ambiente\",\"datePublished\":\"2022-08-24T10:53:44+00:00\",\"dateModified\":\"2022-08-24T11:21:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/\"},\"wordCount\":675,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg\",\"articleSection\":[\"Actualidad\",\"Blog\",\"Fiscal\",\"Jur\u00eddico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/\",\"name\":\"Registro de Entidades de Medio Ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg\",\"datePublished\":\"2022-08-24T10:53:44+00:00\",\"dateModified\":\"2022-08-24T11:21:10+00:00\",\"description\":\"Las entidades no lucrativas que trabajen por el medio ambiente se pueden inscribir en el Registro de Entidades de Medio Ambiente.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Registro de Entidades de Medio Ambiente.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jur\u00eddico\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Todo lo que debes saber sobre el nuevo Registro de Entidades de Medio Ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/fdf6420f515befcbe14be21cbe303807\",\"name\":\"spulido\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"caption\":\"spulido\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/spulido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Registro de Entidades de Medio Ambiente","description":"Las entidades no lucrativas que trabajen por el medio ambiente se pueden inscribir en el Registro de Entidades de Medio Ambiente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/","og_locale":"es_ES","og_type":"article","og_title":"Registro de Entidades de Medio Ambiente","og_description":"Las entidades no lucrativas que trabajen por el medio ambiente se pueden inscribir en el Registro de Entidades de Medio Ambiente.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2022-08-24T10:53:44+00:00","article_modified_time":"2022-08-24T11:21:10+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/08\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg","type":"image\/jpeg"}],"author":"spulido","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"spulido","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/"},"author":{"name":"spulido","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/fdf6420f515befcbe14be21cbe303807"},"headline":"Todo lo que debes saber sobre el nuevo Registro de Entidades de Medio Ambiente","datePublished":"2022-08-24T10:53:44+00:00","dateModified":"2022-08-24T11:21:10+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/"},"wordCount":675,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/08\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg","articleSection":["Actualidad","Blog","Fiscal","Jur\u00eddico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/","name":"Registro de Entidades de Medio Ambiente","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/08\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg","datePublished":"2022-08-24T10:53:44+00:00","dateModified":"2022-08-24T11:21:10+00:00","description":"Las entidades no lucrativas que trabajen por el medio ambiente se pueden inscribir en el Registro de Entidades de Medio Ambiente.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/08\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2022\/08\/hand-of-person-in-blue-latex-glove-picks-up-plastic-bottle-from-the-ground.jpg","width":1500,"height":1000,"caption":"Registro de Entidades de Medio Ambiente."},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/lo-que-debes-saber-sobre-nuevo-registro-entidades-medio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Jur\u00eddico","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/"},{"@type":"ListItem","position":4,"name":"Todo lo que debes saber sobre el nuevo Registro de Entidades de Medio Ambiente"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/fdf6420f515befcbe14be21cbe303807","name":"spulido","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","caption":"spulido"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/spulido\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/20150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/360"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=20150"}],"version-history":[{"count":2,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/20150\/revisions"}],"predecessor-version":[{"id":20151,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/20150\/revisions\/20151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/20135"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=20150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=20150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=20150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}