{"id":22115,"date":"2023-06-21T10:11:19","date_gmt":"2023-06-21T08:11:19","guid":{"rendered":"https:\/\/suport.fundesplai.org\/blog-es\/actualidad\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/"},"modified":"2023-06-21T10:19:27","modified_gmt":"2023-06-21T08:19:27","slug":"como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/","title":{"rendered":"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<div class=\"field field-name-field-resum field-type-text-long field-label-above\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>En los \u00faltimos meses, se ha hablado mucho de <strong>ChatGPT<\/strong>, una herramienta \u00fatil para comunicarse f\u00e1cilmente con un sistema de <strong>inteligencia artificial<\/strong>. Es importante destacar que no es necesario tener conocimientos avanzados en tecnolog\u00eda artificial para utilizarlo, ya que se ha dise\u00f1ado para ser accesible e intuitivo.<\/p>\n<p>Ahora bien, cabe preguntarse si las <strong>entidades del tercer sector<\/strong> pueden aprovechar esta herramienta para mejorar su gesti\u00f3n y comunicaci\u00f3n, a pesar de la limitaci\u00f3n de sus recursos. La respuesta es afirmativa, pero es importante <strong>comprender c\u00f3mo funciona<\/strong> este sistema de inteligencia artificial para saber c\u00f3mo utilizarlo adecuadamente. En este art\u00edculo, te presentamos las bases para entender qu\u00e9 es ChatGPT y c\u00f3mo se puede utilizar en este contexto de una manera muy b\u00e1sica.<\/p>\n<h4>\u00bfC\u00f3mo se accede a ChatGPT?<\/h4>\n<p>Para empezar a utilizar ChatGPT, es necesario acceder al sitio <a href=\"https:\/\/openai.com\/\">web de OpenAI<\/a>, la empresa que ha desarrollado este sistema. Una vez creada la cuenta, ya se puede <strong>escribir la duda o solicitud<\/strong> en la caja de texto disponible. En pocos segundos, ChatGPT <strong>generar\u00e1 una respuesta<\/strong> basada en el an\u00e1lisis del contenido del mensaje. Es importante destacar que ChatGPT es una herramienta de <strong>generaci\u00f3n de conversaciones<\/strong>, ya que tiene la capacidad de comprender lo que se le est\u00e1 preguntando.<\/p>\n<h4>\u00bfC\u00f3mo deben formularse las preguntas o mantener una conversaci\u00f3n?<\/h4>\n<p>Es importante formular las dudas con <strong>precisi\u00f3n<\/strong>. Se puede incluir informaci\u00f3n como el <strong>idioma<\/strong>, el <strong>n\u00famero de palabras<\/strong>, el <strong>tono del texto<\/strong> (informal o formal) o la complejidad deseada de la respuesta. Tambi\u00e9n se puede especificar el prop\u00f3sito o enfoque de lo que se est\u00e1 pidiendo, ya que un texto para personas expertas no ser\u00e1 igual que para principiantes.<\/p>\n<p>Al tratarse de una conversaci\u00f3n, la persona puede ajustar o concretar sus preguntas o comentarios a medida que avanza la interacci\u00f3n. Hay que tener en cuenta que es preferible <strong>evitar los dobles sentidos<\/strong>, la iron\u00eda o el humor, puesto que este sistema de inteligencia artificial puede tener dificultades para interpretarlo.<\/p>\n<h4>\u00bfPara qu\u00e9 pueden utilizar las entidades ChatGPT?<\/h4>\n<p><strong>\u200b<\/strong>Las entidades sin \u00e1nimo de lucro pueden utilizar esta herramienta para <strong>responder preguntas<\/strong> recibidas -siempre con supervisi\u00f3n-, mejorar la comunicaci\u00f3n interna de la organizaci\u00f3n, preparar guiones para formaciones, preparar documentos con formatos espec\u00edficos, crear contenidos para las redes sociales o el blog, planificar un calendario de contenidos para las redes o revisar textos. Por tanto, hay infinitas posibilidades que se pueden probar.<\/p>\n<p>Hay que tener en cuenta que ChatGPT es un sistema basado en <strong>aprendizaje autom\u00e1tico<\/strong>, est\u00e1 en fase de desarrollo y mejora continua. Esto significa que, aunque puede proporcionar respuestas precisas, todav\u00eda no es capaz de comprender completamente el contexto o la intenci\u00f3n de un mensaje de la misma forma que lo har\u00eda un ser humano. Por tanto, es importante tener paciencia y entender que en ocasiones las respuestas pueden ser poco claras o incompletas.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\">\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<h4>C\u00f3mo redactar contenidos con la ayuda de ChatGPT<\/h4>\n<p>Para las entidades que desean escribir <strong>art\u00edculos para su blog<\/strong>, ChatGPT puede ser una herramienta muy valiosa para <strong>generar ideas y contenidos<\/strong> . Se puede introducir una palabra clave relacionada con el tema del art\u00edculo. Por ejemplo, si el objetivo es publicar un contenido sobre los beneficios del ejercicio, puede insertarse \u00abventajas del ejercicio\u00bb en el campo de texto.<\/p>\n<p>A partir de la respuesta generada por ChatGPT, se pueden obtener ideas para la redacci\u00f3n del art\u00edculo. Esta respuesta inicial puede servir como punto de partida para profundizar en la investigaci\u00f3n sobre el tema y a\u00f1adir informaci\u00f3n adicional.<\/p>\n<p>En caso de que tengamos varias ideas e informaci\u00f3n a a\u00f1adir, deben especificarse para que el sistema las pueda tener en cuenta. En cualquier caso, es necesario revisar cuidadosamente la propuesta que da ChatGPT.<\/p>\n<h4>C\u00f3mo gestionar las respuestas de ChatGPT de forma adecuada<\/h4>\n<p>Es desaconsejable simplemente copiar y pegar la respuesta generada por ChatGPT, ya que puede contener <strong>inexactitudes o errores<\/strong>. Es importante <strong>personalizar la redacci\u00f3n<\/strong> para adaptarla al propio estilo y p\u00fablico objetivo.<\/p>\n<p>Aunque existen ejemplos de contenidos creados exclusivamente por ChatGPT, y existen debates sobre si la inteligencia artificial sustituir\u00e1 a los redactores humanos, es recomendable considerar la respuesta obtenida como un punto de partida.<\/p>\n<p>En el caso de las entidades, es esencial que las personas responsables puedan aportar su <strong>experiencia<\/strong>, <strong>ejemplos reales<\/strong>, <strong>testimonios<\/strong>, etc., para dar mayor calidad al contenido. Este valor a\u00f1adido es el que valora la audiencia y que le diferencia de cualquier otro contenido que pueda encontrarse en internet.<\/p>\n<h4>Otras utilidades de ChatGPT<\/h4>\n<p>Otra utilidad aplicable a las organizaciones sin \u00e1nimo de lucro es la <strong>creaci\u00f3n de contenido para redes sociales<\/strong>, planteando posibles tem\u00e1ticas a tratar, consejos sobre el uso de las redes sociales o la elaboraci\u00f3n de un gui\u00f3n para su publicaci\u00f3n. Este sistema tambi\u00e9n puede ser \u00fatil para redactar correos electr\u00f3nicos a partir de una idea o reescribir y mejorar textos. Hay que tener en cuenta que cada vez m\u00e1s herramientas est\u00e1n incorporando la <strong>inteligencia artificial<\/strong>, por ejemplo, <a href=\"https:\/\/xarxanet.org\/informatic\/noticies\/5-novetats-de-metricool-gestionar-xarxes-socials-que-poden-ser-dutilitat-les\" target=\"_blank\" rel=\"noopener\">Metricool<\/a> permite redactar textos para las publicaciones con este sistema.<\/p>\n<p>Por tanto, ChatGPT puede ser una herramienta que facilite algunos aspectos de la gesti\u00f3n de las organizaciones. Sin embargo, es importante <strong>practicar<\/strong> para entender el funcionamiento de este sistema de inteligencia artificial y siempre es necesario <strong>revisar<\/strong> las respuestas obtenidas. A pesar de tener gran potencial, las personas con pocos conocimientos tambi\u00e9n pueden interactuar con \u00e9l en acciones m\u00e1s b\u00e1sicas.<\/p>\n<p>Fuente: redactado por el equipo de Suport Tercer Sector para <a href=\"https:\/\/xarxanet.org\/informatic\/noticies\/que-es-pot-fer-servir-chatgpt\" target=\"_blank\" rel=\"noopener\">Xarxanet.<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ChatGPT es una herramienta muy potente que las entidades sin \u00e1nimo de lucro pueden utilizar para mejorar su gesti\u00f3n.<\/p>\n","protected":false},"author":360,"featured_media":22042,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,341,321,312],"tags":[],"class_list":["post-22115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-blog-es","category-comunicacion","category-informatico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?<\/title>\n<meta name=\"description\" content=\"ChatGPT es una herramienta muy potente que las entidades sin \u00e1nimo de lucro pueden utilizar para mejorar su gesti\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?\" \/>\n<meta property=\"og:description\" content=\"ChatGPT es una herramienta muy potente que las entidades sin \u00e1nimo de lucro pueden utilizar para mejorar su gesti\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-21T08:11:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T08:19:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/06\/chatgpt-entitats-no-lucratives.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"spulido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"spulido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/\"},\"author\":{\"name\":\"spulido\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/fdf6420f515befcbe14be21cbe303807\"},\"headline\":\"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?\",\"datePublished\":\"2023-06-21T08:11:19+00:00\",\"dateModified\":\"2023-06-21T08:19:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/\"},\"wordCount\":1019,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/chatgpt-entitats-no-lucratives.png\",\"articleSection\":[\"Actualidad\",\"Blog\",\"Comunicaci\u00f3n\",\"Inform\u00e1tico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/\",\"name\":\"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/chatgpt-entitats-no-lucratives.png\",\"datePublished\":\"2023-06-21T08:11:19+00:00\",\"dateModified\":\"2023-06-21T08:19:27+00:00\",\"description\":\"ChatGPT es una herramienta muy potente que las entidades sin \u00e1nimo de lucro pueden utilizar para mejorar su gesti\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/chatgpt-entitats-no-lucratives.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/chatgpt-entitats-no-lucratives.png\",\"width\":1888,\"height\":900,\"caption\":\"Chatgpt per a entitats sense \u00e0nim de lucre.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Comunicaci\u00f3n\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/fdf6420f515befcbe14be21cbe303807\",\"name\":\"spulido\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"caption\":\"spulido\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/spulido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?","description":"ChatGPT es una herramienta muy potente que las entidades sin \u00e1nimo de lucro pueden utilizar para mejorar su gesti\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?","og_description":"ChatGPT es una herramienta muy potente que las entidades sin \u00e1nimo de lucro pueden utilizar para mejorar su gesti\u00f3n.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2023-06-21T08:11:19+00:00","article_modified_time":"2023-06-21T08:19:27+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/06\/chatgpt-entitats-no-lucratives.png","type":"image\/png"}],"author":"spulido","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"spulido","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/"},"author":{"name":"spulido","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/fdf6420f515befcbe14be21cbe303807"},"headline":"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?","datePublished":"2023-06-21T08:11:19+00:00","dateModified":"2023-06-21T08:19:27+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/"},"wordCount":1019,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/06\/chatgpt-entitats-no-lucratives.png","articleSection":["Actualidad","Blog","Comunicaci\u00f3n","Inform\u00e1tico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/","name":"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/06\/chatgpt-entitats-no-lucratives.png","datePublished":"2023-06-21T08:11:19+00:00","dateModified":"2023-06-21T08:19:27+00:00","description":"ChatGPT es una herramienta muy potente que las entidades sin \u00e1nimo de lucro pueden utilizar para mejorar su gesti\u00f3n.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/06\/chatgpt-entitats-no-lucratives.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/06\/chatgpt-entitats-no-lucratives.png","width":1888,"height":900,"caption":"Chatgpt per a entitats sense \u00e0nim de lucre."},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/como-utilizar-chatgpt-en-la-comunicacion-del-tercer-sector\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Comunicaci\u00f3n","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/"},{"@type":"ListItem","position":4,"name":"\u00bfC\u00f3mo utilizar ChatGPT en la comunicaci\u00f3n del tercer sector?"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/fdf6420f515befcbe14be21cbe303807","name":"spulido","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","caption":"spulido"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/spulido\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/22115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/360"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=22115"}],"version-history":[{"count":4,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/22115\/revisions"}],"predecessor-version":[{"id":22121,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/22115\/revisions\/22121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/22042"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=22115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=22115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=22115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}