{"id":24693,"date":"2024-01-04T09:28:33","date_gmt":"2024-01-04T08:28:33","guid":{"rendered":"https:\/\/suport.fundesplai.org\/blog-es\/actualidad\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/"},"modified":"2024-01-19T10:24:44","modified_gmt":"2024-01-19T09:24:44","slug":"subvenciones-2024-convo24-que-es-y-como-se-solicita","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/","title":{"rendered":"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p>El Departament de Drets Socials de la Generalitat ha publicado ya las <a href=\"https:\/\/dogc.gencat.cat\/ca\/document-del-dogc\/?documentId=974573\" target=\"_blank\" rel=\"noopener\">bases reguladoras<\/a> para su convocatoria de subvenciones del a\u00f1o, uno de los tr\u00e1mites m\u00e1s importantes que las entidades del tercer sector tienen marcado en el calendario. Este a\u00f1o, se presenta la <strong>CONVO24<\/strong>, una novedad en la gesti\u00f3n que fusiona las anteriores l\u00edneas de ayuda del IRPF y de la COSPE. Por esta raz\u00f3n, es necesario revisar con previsi\u00f3n suficiente en qu\u00e9 l\u00edneas se quiere presentar cada proyecto.<\/p>\n<p>Se prev\u00e9n un total de 102 l\u00edneas de ayuda, que se dividen en cuatro grandes tipolog\u00edas:<\/p>\n<ol>\n<li>Subvenciones a <strong>proyectos experimentales de atenci\u00f3n a las personas<\/strong> en el \u00e1mbito de servicios sociales.<\/li>\n<li>Subvenciones a proyectos de inversi\u00f3n de construcci\u00f3n, remodelaci\u00f3n o equipamiento de establecimientos de servicios sociales incluidos en la Red de Servicios Sociales. de Atenci\u00f3 P\u00fablica o en la Xarxa Catalana d&#8217;Instal\u00b7lacions Juvenils o en la Xarxa de Punts \u00d2mnia.<\/li>\n<li>Subvenciones de <strong>promoci\u00f3n de actividades y programas de entidades sociales.<\/strong><\/li>\n<li>Subvenciones de <strong>promoci\u00f3n de los servicios prestados por entidades federativas<\/strong> de segundo y tercer orden.<\/li>\n<\/ol>\n<h3>Principales l\u00edneas de la CONVO24<\/h3>\n<p>En este sentido, la Direcci\u00f3 <a href=\"https:\/\/dretssocials.gencat.cat\/ca\/el_departament\/funcions_i_estructura\/estructura\/secretaria-dafers-socials-i-families\/direccio-general-daccio-civica-i-comunitaria\/index.html\" target=\"_blank\" rel=\"noopener\">General d&#8217;Acci\u00f3 C\u00edvica i Comunit\u00e0ria<\/a> mantiene <a href=\"https:\/\/voluntariat.gencat.cat\/publicades-les-bases-que-han-de-regir-la-convocatoria-ordinaria-de-subvencions-a-entitats-de-lambit-de-politiques-socials-del-departament-de-drets-socials-per-a-lany-2024\/\" target=\"_blank\" rel=\"noopener\">tres de sus l\u00edneas<\/a> y ampl\u00eda una cuarta en el \u00e1mbito del asociacionismo y el voluntariado:<\/p>\n<ul>\n<li>Actividades y proyectos de formaci\u00f3n. Voluntariado.<\/li>\n<li>Actividades y proyectos de soporte a entidades, profesionales y personas voluntarias. Fortalecimiento del asociacionismo.<\/li>\n<li>Actividades y proyectos de soporte a entidades, profesionales y personas voluntarias. Promoci\u00f3n y fomento del voluntariado.<\/li>\n<li>Actividades y programas de acompa\u00f1amiento. Mentor\u00eda social.<\/li>\n<\/ul>\n<p>Adem\u00e1s, es necesario tener en cuenta otras l\u00edneas de ayuda relacionadas con proyectos de educaci\u00f3n en valores y ocio, apoyo al Pueblo Gitano o fomento del envejecimiento activo.<\/p>\n<p>La Generalitat ha publicado la nueva <a href=\"https:\/\/web.gencat.cat\/web\/shared\/OVT\/Departaments\/DSO\/Documents_i_enllacos\/SG\/CONVO-subvencions\/Guia-de-Projectes-2024.pdf\" target=\"_blank\" rel=\"noopener\">Gu\u00eda de proyectos<\/a>, actualizada el 13 de enero, en la que hace una explicaci\u00f3n exhaustiva de todas las l\u00edneas convocadas, as\u00ed como de los criterios de valoraci\u00f3n o no admisi\u00f3n. En este documento tambi\u00e9n puede encontrarse la relaci\u00f3n de las l\u00edneas de la <a href=\"https:\/\/xarxanet.org\/economic\/noticies\/publicades-les-bases-de-la-convocatoria-ordinaria-de-subvencions-del-departament\" target=\"_blank\" rel=\"noopener\">nueva CONVO24<\/a> con las convocatorias de los a\u00f1os anteriores.<\/p>\n<h3>\u00bfQui\u00e9n puede recibir ayudas de la CONVO24?<\/h3>\n<p>Esta subvenci\u00f3n <strong>s\u00f3lo se otorga a las entidades sin \u00e1nimo de lucro<\/strong> constituidas legalmente, al menos con dos a\u00f1os de anterioridad, que est\u00e9n establecidas y ejerzan su actividad en Catalu\u00f1a.<\/p>\n<p>Por otra parte, no pueden beneficiarse las entidades vinculadas a las administraciones p\u00fablicas. Tampoco pueden acceder aquellas entidades en las que haya ning\u00fan tipo de discriminaci\u00f3n por raz\u00f3n de sexo o bien orientaci\u00f3n sexual, diversidad \u00e9tnica, cultural&#8230;<\/p>\n<h3>\u00bfC\u00f3mo solicitar subvenciones a la CONVO24?<\/h3>\n<p>La solicitud se hace, \u00fanicamente, de forma telem\u00e1tica <strong>del 2 hasta el 29 de enero, a las 15 h<\/strong> . Para hacerla, basta con acceder a la <a href=\"https:\/\/web.gencat.cat\/ca\/tramits\/tramits-temes\/subvencions-entitats-ambit-politiques-socials-departament-drets-socials?moda=1\" target=\"_blank\" rel=\"noopener\">web<\/a> y rellenar el formulario. Por otra parte, para facilitar la tarea, el Departament de Drets Socials ha publicado un v\u00eddeo explicativo que detalla c\u00f3mo presentar la solicitud y los anexos.<\/p>\n<p>[\/et_pb_text][et_pb_video src=\u00bbhttps:\/\/www.youtube.com\/watch?v=e5KeC-5uR1g\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_video][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La CONVO24 es la nueva convocatoria de subvenciones del Departament de Drets Socials que muchas entidades sin \u00e1nimo de lucro deben tener en cuenta.<\/p>\n","protected":false},"author":360,"featured_media":24651,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1,341,285],"tags":[],"class_list":["post-24693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-blog-es","category-economico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita<\/title>\n<meta name=\"description\" content=\"CONVO24 es la nueva convocatoria de subvenciones del Departament de Drets Socials para entidades sin \u00e1nimo de lucro.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita\" \/>\n<meta property=\"og:description\" content=\"CONVO24 es la nueva convocatoria de subvenciones del Departament de Drets Socials para entidades sin \u00e1nimo de lucro.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-04T08:28:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-19T09:24:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/01\/subvencions-2024-convo24-suport-tercer-sector.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"spulido\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"spulido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/\"},\"author\":{\"name\":\"spulido\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/fdf6420f515befcbe14be21cbe303807\"},\"headline\":\"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita\",\"datePublished\":\"2024-01-04T08:28:33+00:00\",\"dateModified\":\"2024-01-19T09:24:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/\"},\"wordCount\":627,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/subvencions-2024-convo24-suport-tercer-sector.png\",\"articleSection\":[\"Actualidad\",\"Blog\",\"Econ\u00f3mico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/\",\"name\":\"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/subvencions-2024-convo24-suport-tercer-sector.png\",\"datePublished\":\"2024-01-04T08:28:33+00:00\",\"dateModified\":\"2024-01-19T09:24:44+00:00\",\"description\":\"CONVO24 es la nueva convocatoria de subvenciones del Departament de Drets Socials para entidades sin \u00e1nimo de lucro.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/subvencions-2024-convo24-suport-tercer-sector.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/subvencions-2024-convo24-suport-tercer-sector.png\",\"width\":1888,\"height\":900,\"caption\":\"Convo24, subvencions per a entitats del tercer sector.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/subvenciones-2024-convo24-que-es-y-como-se-solicita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Econ\u00f3mico\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/fdf6420f515befcbe14be21cbe303807\",\"name\":\"spulido\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g\",\"caption\":\"spulido\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/spulido\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita","description":"CONVO24 es la nueva convocatoria de subvenciones del Departament de Drets Socials para entidades sin \u00e1nimo de lucro.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/","og_locale":"es_ES","og_type":"article","og_title":"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita","og_description":"CONVO24 es la nueva convocatoria de subvenciones del Departament de Drets Socials para entidades sin \u00e1nimo de lucro.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2024-01-04T08:28:33+00:00","article_modified_time":"2024-01-19T09:24:44+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/01\/subvencions-2024-convo24-suport-tercer-sector.png","type":"image\/png"}],"author":"spulido","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"spulido","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/"},"author":{"name":"spulido","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/fdf6420f515befcbe14be21cbe303807"},"headline":"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita","datePublished":"2024-01-04T08:28:33+00:00","dateModified":"2024-01-19T09:24:44+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/"},"wordCount":627,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/01\/subvencions-2024-convo24-suport-tercer-sector.png","articleSection":["Actualidad","Blog","Econ\u00f3mico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/","name":"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/01\/subvencions-2024-convo24-suport-tercer-sector.png","datePublished":"2024-01-04T08:28:33+00:00","dateModified":"2024-01-19T09:24:44+00:00","description":"CONVO24 es la nueva convocatoria de subvenciones del Departament de Drets Socials para entidades sin \u00e1nimo de lucro.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/01\/subvencions-2024-convo24-suport-tercer-sector.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/01\/subvencions-2024-convo24-suport-tercer-sector.png","width":1888,"height":900,"caption":"Convo24, subvencions per a entitats del tercer sector."},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/subvenciones-2024-convo24-que-es-y-como-se-solicita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Econ\u00f3mico","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/"},{"@type":"ListItem","position":4,"name":"Subvenciones 2024: CONVO24, qu\u00e9 es y c\u00f3mo se solicita"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/fdf6420f515befcbe14be21cbe303807","name":"spulido","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/efd3238af867ca2ea7ff51cd3989f365e8f2a9e617574ce9b528f93010322b3d?s=96&d=monsterid&r=g","caption":"spulido"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/spulido\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/24693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/360"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=24693"}],"version-history":[{"count":11,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/24693\/revisions"}],"predecessor-version":[{"id":24805,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/24693\/revisions\/24805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/24651"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=24693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=24693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=24693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}