{"id":28831,"date":"2024-10-08T09:42:56","date_gmt":"2024-10-08T07:42:56","guid":{"rendered":"https:\/\/suport.fundesplai.org\/blog-es\/actualidad\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/"},"modified":"2024-10-08T09:47:41","modified_gmt":"2024-10-08T07:47:41","slug":"conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/","title":{"rendered":"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Saps<strong> qu\u00e8 \u00e9s la menosfera<\/strong>? Vols entendre com les xarxes socials difonen idees com el masclisme? Durant el primer episodi de la segona temporada del p\u00f2dcast \u2018Entitats al dia\u2019 abordem temes tan importants com la <strong>perpetuaci\u00f3 de les viol\u00e8ncies masclistes a trav\u00e9s d\u2019internet<\/strong>, les xarxes socials i els mitjans de comunicaci\u00f3.<\/p>\n<p>Escolta el primer episodi de la <strong>nova temporada del programa \u2018Entitats al dia\u2019<\/strong> i ent\u00e9n com pots detectar aquests comportaments per aturar-los i quin paper en poden tenir les entitats no lucratives!<\/p>\n<p>Recorda que des de <strong>Suport Tercer Sector<\/strong> tenim disponible l<a href=\"https:\/\/suport.fundesplai.org\/es\/servicios\/oficina-tecnica-para-la-equidad-de-genero-y-la-diversidad-sexual\/\">\u2019Oficina\u00a0t\u00e8cnica\u00a0per a l\u2019equitat de g\u00e8nere i la diversitat sexual<\/a> on les entitats poden enviar les seves consultes sobre aquests temes.<\/p>\n<h3><strong>On es pot escoltar el p\u00f2dcast?<\/strong><\/h3>\n<p>Cada dimarts i dijous es publicar\u00e0 un nou episodi en les plataformes\u00a0<a href=\"https:\/\/www.ivoox.com\/podcast-entitats-al-dia_sq_f12318091_1.html\">Ivoox<\/a> i <a href=\"https:\/\/podcasters.spotify.com\/pod\/show\/entitats-al-dia\/episodes\/La-conciliaci-laboral-i-personal-a-les-entitats-e2bjjmm\">Spotify.<\/a><\/p>\n<p><iframe loading=\"lazy\" src=\"https:\/\/www.ivoox.com\/player_ej_133845078_6_1.html?c1=045c2c\" width=\"100%\" height=\"200\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/www.ivoox.com\/en\/2&#215;01-la-violencia-genere-prevencio-deteccio-audios-mp3_rf_133845078_1.html\u00bb button_text=\u00bbIvoox\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/podcasters.spotify.com\/pod\/show\/entitats-al-dia\/episodes\/2&#215;01&#8211;La-violncia-de-gnere-prevenci&#8211;detecci-i-abordatge-des-de-lentitat-e2oa750&#8243; button_text=\u00bbSpotify\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><strong>Qu\u00e8 \u00e9s la menosfera?<\/strong><\/h3>\n<p>L\u2019Aroa Abellan, la convidada del programa, \u00e9s<strong> t\u00e8cnica de l\u2019\u00e0rea d\u2019Igualtat i Diversitat de Suport Tercer Sector de Fundesplai<\/strong>. Ella \u00e9s l\u2019encarregada d\u2019explicar, entre altres coses, qu\u00e8 significa aquest terme desconegut per a moltes persones: la menosfera.<\/p>\n<p>\u00c9s la xarxa d\u2019espais (<em>online<\/em> o <em>offline<\/em>) en la qual<strong> es promou i alimenta el masclisme i l\u2019odi dirigit a la dona.<\/strong> Les persones que hi participen situen l\u2019home com la v\u00edctima del sistema. Per tant, entenen que l\u2019aven\u00e7 cap a la igualtat o equitat de les persones s\u00f3n un retroc\u00e9s dels seus drets i rols. Gr\u00e0cies a les plataformes han trobat <strong>nous espais on alimentar el seu ideari i sentir-se segurs<\/strong>.<\/p>\n<p>Per culpa del disseny de les xarxes socials, l\u2019algoritme posiciona el contingut per captar el m\u00e0xim de p\u00fablic i retenir-lo tant temps com sigui possible. Qualsevol, incloent-hi persones joves,<strong> t\u00e9 acc\u00e9s molt r\u00e0pid i directe a aquesta falsa informaci\u00f3<\/strong>. Socialitzant d\u2019aquesta manera <strong>poden esdevenir persones adultes mis\u00f2gines<\/strong>, amb les conseq\u00fc\u00e8ncies que aix\u00f2 pot tenir en el seu comportament envers les persones.<\/p>\n<p><strong>Les entitats s\u00f3n agents de canvi<\/strong> que poden tenir un impacte molt directe amb infants i joves. Aquelles que treballen amb inf\u00e0ncia i joventut s\u00f3n les que poden fer la feina pedag\u00f2gica perqu\u00e8 esdevinguin persones adultes cr\u00edtiques i amb capacitat de raonament.<\/p>\n<p>Si vols saber m\u00e9s sobre aquest tema i molts altres relacionats amb les entitats, no deixis d\u2019escoltar el p\u00f2dcast <strong>\u2018Entitats al dia\u2019<\/strong>. Amb la col\u00b7laboraci\u00f3 del Departament de Cultura de la Generalitat de Catalunya.<\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.21.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Aquest projecte es duu a terme amb el suport del <strong><a href=\"http:\/\/llengua.gencat.cat\/ca\/inici\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">Departament de Cultura de la Generalitat de Catalunya.<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-24931 size-full alignleft\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/11\/cultura_h2.png\" alt=\"\" width=\"681\" height=\"110\" srcset=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/11\/cultura_h2.png 681w, https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2023\/11\/cultura_h2-480x78.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 681px, 100vw\" \/><\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conoce qu\u00e9 es la menosfera y c\u00f3mo las entidades pueden jugar un papel importante contra el machismo.<\/p>\n","protected":false},"author":402,"featured_media":28776,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,341,321],"tags":[],"class_list":["post-28831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-blog-es","category-comunicacion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales - Suport Tercer Sector - Fundesplai<\/title>\n<meta name=\"description\" content=\"Conoce qu\u00e9 es la menosfera y c\u00f3mo las entidades pueden jugar un papel importante contra el machismo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales - Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Conoce qu\u00e9 es la menosfera y c\u00f3mo las entidades pueden jugar un papel importante contra el machismo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-08T07:42:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-08T07:47:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/10\/Fotos-blog-Suport-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"oscar.loro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"oscar.loro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/\"},\"author\":{\"name\":\"oscar.loro\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/0ff031aadbf63e105539f995878f9224\"},\"headline\":\"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales\",\"datePublished\":\"2024-10-08T07:42:56+00:00\",\"dateModified\":\"2024-10-08T07:47:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/\"},\"wordCount\":801,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Fotos-blog-Suport-2.png\",\"articleSection\":[\"Actualidad\",\"Blog\",\"Comunicaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/\",\"name\":\"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales - Suport Tercer Sector - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Fotos-blog-Suport-2.png\",\"datePublished\":\"2024-10-08T07:42:56+00:00\",\"dateModified\":\"2024-10-08T07:47:41+00:00\",\"description\":\"Conoce qu\u00e9 es la menosfera y c\u00f3mo las entidades pueden jugar un papel importante contra el machismo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Fotos-blog-Suport-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Fotos-blog-Suport-2.png\",\"width\":1888,\"height\":900,\"caption\":\"Aturem el masclisme a la manosfera\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/comunicacion\\\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Actualidad\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/actualidad\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/0ff031aadbf63e105539f995878f9224\",\"name\":\"oscar.loro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g\",\"caption\":\"oscar.loro\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/oscar-loro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales - Suport Tercer Sector - Fundesplai","description":"Conoce qu\u00e9 es la menosfera y c\u00f3mo las entidades pueden jugar un papel importante contra el machismo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/","og_locale":"es_ES","og_type":"article","og_title":"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales - Suport Tercer Sector - Fundesplai","og_description":"Conoce qu\u00e9 es la menosfera y c\u00f3mo las entidades pueden jugar un papel importante contra el machismo.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2024-10-08T07:42:56+00:00","article_modified_time":"2024-10-08T07:47:41+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/10\/Fotos-blog-Suport-2.png","type":"image\/png"}],"author":"oscar.loro","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"oscar.loro","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/"},"author":{"name":"oscar.loro","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/0ff031aadbf63e105539f995878f9224"},"headline":"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales","datePublished":"2024-10-08T07:42:56+00:00","dateModified":"2024-10-08T07:47:41+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/"},"wordCount":801,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/10\/Fotos-blog-Suport-2.png","articleSection":["Actualidad","Blog","Comunicaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/","name":"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales - Suport Tercer Sector - Fundesplai","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/10\/Fotos-blog-Suport-2.png","datePublished":"2024-10-08T07:42:56+00:00","dateModified":"2024-10-08T07:47:41+00:00","description":"Conoce qu\u00e9 es la menosfera y c\u00f3mo las entidades pueden jugar un papel importante contra el machismo.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/10\/Fotos-blog-Suport-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/10\/Fotos-blog-Suport-2.png","width":1888,"height":900,"caption":"Aturem el masclisme a la manosfera"},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/comunicacion\/conoce-como-se-difunde-el-machismo-a-traves-de-las-redes-sociales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Actualidad","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/actualidad\/"},{"@type":"ListItem","position":4,"name":"Conoce c\u00f3mo se difunde el machismo a trav\u00e9s de las redes sociales"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/0ff031aadbf63e105539f995878f9224","name":"oscar.loro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g","caption":"oscar.loro"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/oscar-loro\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/28831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/402"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=28831"}],"version-history":[{"count":3,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/28831\/revisions"}],"predecessor-version":[{"id":28837,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/28831\/revisions\/28837"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/28776"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=28831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=28831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=28831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}