{"id":31551,"date":"2025-03-11T09:10:31","date_gmt":"2025-03-11T08:10:31","guid":{"rendered":"https:\/\/suport.fundesplai.org\/?p=31551"},"modified":"2025-04-23T11:36:35","modified_gmt":"2025-04-23T09:36:35","slug":"lgtbi-fobia-en-las-entidades-protocolos-para-combatirla","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/","title":{"rendered":"LGTBI-fobia en las entidades: protocolos para combatirla"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||22px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbEntradilla\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]\u00c0frica Mir\u00f3 y Eduardo Izquierdo han preparado un programa de <strong><a href=\"https:\/\/suport.fundesplai.org\/es\/projecte\/podcast-entitats-al-dia\/\">Entitats al daa<\/a><\/strong> enfocado a explicar <strong>por qu\u00e9 es importante<\/strong> tener protocolos para <strong>combatir la LGTBI-fobia en las entidades.<\/strong><\/p>\n<p>Para analizar este gran tema, han invitado a Aroa Abellan, t\u00e9cnica de <a href=\"https:\/\/suport.fundesplai.org\/es\/servicios\/oficina-tecnica-para-la-equidad-de-genero-y-la-diversidad-sexual\/\">Igualdad y Diversidad de Suport Tercer Sector<\/a> y formadora en los \u00e1mbitos de g\u00e9nero, diversidad de trato y no discriminaci\u00f3n, y Jordy Cererols, tambi\u00e9n del equipo de Suport.<br \/>\n[\/et_pb_text][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text admin_label=\u00bbURL\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<iframe loading=\"lazy\" style=\"border-radius: 12px;\" src=\"https:\/\/open.spotify.com\/embed\/episode\/0yWhmpky1mQ41xHXqq0n68?utm_source=generator\" width=\"100%\" height=\"352\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbTexto 2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Cererols es una persona trabajadora de Suport Tercer Sector que utiliza <strong>pronombres masculinos y femeninos,<\/strong> y explica muchos de los problemas derivados de la LGTBI-fobia que se encuentran las personas de la comunidad durante su d\u00eda a d\u00eda. Aroa y Jordy se adentran en este mundo que es para <strong>muchas personas desconocido<\/strong>. <\/p>\n<p>\u00bfQu\u00e9 es la cisheteronormatividad? \u00bfQu\u00e9 es el patriarcado? \u00bfC\u00f3mo afecta a las personas del colectivo LGTBI no tener un protocolo en su espacio laboral? <strong>\u00bfPor qu\u00e9 es importante tenerlos<\/strong>?  <\/p>\n<p>Jordy y Aroa dan su punto de vista de c\u00f3mo afecta al heteropatriarcado a la vida de las personas y tambi\u00e9n dan unas medidas de inclusividad para que las entidades puedan adoptar y <strong>convertirse en espacios seguros<\/strong>.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/open.spotify.com\/episode\/0yWhmpky1mQ41xHXqq0n68&#8243; url_new_window=\u00bbon\u00bb button_text=\u00bbSpotify\u00bb button_alignment=\u00bbcenter\u00bb admin_label=\u00bbSpotify\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/www.ivoox.com\/2&#215;08-protocols-per-combatre-lgtbifobia-a-les-audios-mp3_rf_135418307_1.html\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbivoox\u00bb button_alignment=\u00bbcenter\u00bb admin_label=\u00bbIvoox\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text admin_label=\u00bbTexto 3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]Este proyecto se lleva a cabo con el soporte del <strong><a href=\"http:\/\/llengua.gencat.cat\/ca\/inici\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-auth=\"NotApplicable\">Departament de Cultura de la Generalitat de Catalunya.<\/a><\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-28380 alignnone size-full\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2024\/09\/generalitat_catalunya_cultura.jpg\" alt=\"\" width=\"456\" height=\"106\"><br \/>\n[\/et_pb_text][et_pb_divider _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text admin_label=\u00bbText\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h4>Otros contenidos relacionados<\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/actualidad\/captacion-de-fondos-uno-de-los-retos\/\" target=\"_blank\" rel=\"noopener\">Captaci\u00f3n de fondos: uno de los retos<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/blog\/actualitat-blog\/podcast-entitats-al-dia-gestio-entitats\/\" target=\"_blank\" rel=\"noopener\">Escucha el podcast &#8216;Entitats al dia&#8217; para mejorar la gesti\u00f3n de tu organizaci\u00f3n<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/actualidad\/entitats-al-dia-el-fomento-del-catalan\/\" target=\"_blank\" rel=\"noopener\">Entitats al dia: el fomento del catal\u00e1n<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<br \/>\n[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Combatir la LGTBI-fobia es importante para las entidades y para las personas que trabajan en ellas. Son un paraguas de seguridad que ayuda a que se sientan m\u00e1s protegidas. <\/p>\n","protected":false},"author":402,"featured_media":31542,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[1,341,896],"tags":[],"class_list":["post-31551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-blog-es","category-recursos-igualdad"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LGTBI-fobia en las entidades: protocolos para combatirla - Suport Tercer Sector - Fundesplai<\/title>\n<meta name=\"description\" content=\"Combatir la LGTBI-fobia es importante y para hacerlo se necesitan protocolos. &#039;Entidades al d\u00eda&#039; lo analiza.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LGTBI-fobia en las entidades: protocolos para combatirla - Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Combatir la LGTBI-fobia es importante y para hacerlo se necesitan protocolos. &#039;Entidades al d\u00eda&#039; lo analiza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T08:10:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T09:36:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/03\/Ciberseguretat-1-1200x572.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"572\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"oscar.loro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"oscar.loro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/\"},\"author\":{\"name\":\"oscar.loro\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/0ff031aadbf63e105539f995878f9224\"},\"headline\":\"LGTBI-fobia en las entidades: protocolos para combatirla\",\"datePublished\":\"2025-03-11T08:10:31+00:00\",\"dateModified\":\"2025-04-23T09:36:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/\"},\"wordCount\":617,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciberseguretat-1.png\",\"articleSection\":[\"Actualidad\",\"Blog\",\"Recursos igualdad y diversidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/\",\"name\":\"LGTBI-fobia en las entidades: protocolos para combatirla - Suport Tercer Sector - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciberseguretat-1.png\",\"datePublished\":\"2025-03-11T08:10:31+00:00\",\"dateModified\":\"2025-04-23T09:36:35+00:00\",\"description\":\"Combatir la LGTBI-fobia es importante y para hacerlo se necesitan protocolos. 'Entidades al d\u00eda' lo analiza.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciberseguretat-1.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Ciberseguretat-1.png\",\"width\":1888,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recursos igualdad y diversidad\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/recursos-igualdad\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"LGTBI-fobia en las entidades: protocolos para combatirla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/0ff031aadbf63e105539f995878f9224\",\"name\":\"oscar.loro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g\",\"caption\":\"oscar.loro\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/oscar-loro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LGTBI-fobia en las entidades: protocolos para combatirla - Suport Tercer Sector - Fundesplai","description":"Combatir la LGTBI-fobia es importante y para hacerlo se necesitan protocolos. 'Entidades al d\u00eda' lo analiza.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/","og_locale":"es_ES","og_type":"article","og_title":"LGTBI-fobia en las entidades: protocolos para combatirla - Suport Tercer Sector - Fundesplai","og_description":"Combatir la LGTBI-fobia es importante y para hacerlo se necesitan protocolos. 'Entidades al d\u00eda' lo analiza.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2025-03-11T08:10:31+00:00","article_modified_time":"2025-04-23T09:36:35+00:00","og_image":[{"width":1200,"height":572,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/03\/Ciberseguretat-1-1200x572.png","type":"image\/png"}],"author":"oscar.loro","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"oscar.loro","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/"},"author":{"name":"oscar.loro","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/0ff031aadbf63e105539f995878f9224"},"headline":"LGTBI-fobia en las entidades: protocolos para combatirla","datePublished":"2025-03-11T08:10:31+00:00","dateModified":"2025-04-23T09:36:35+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/"},"wordCount":617,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/03\/Ciberseguretat-1.png","articleSection":["Actualidad","Blog","Recursos igualdad y diversidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/","name":"LGTBI-fobia en las entidades: protocolos para combatirla - Suport Tercer Sector - Fundesplai","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/03\/Ciberseguretat-1.png","datePublished":"2025-03-11T08:10:31+00:00","dateModified":"2025-04-23T09:36:35+00:00","description":"Combatir la LGTBI-fobia es importante y para hacerlo se necesitan protocolos. 'Entidades al d\u00eda' lo analiza.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/03\/Ciberseguretat-1.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/03\/Ciberseguretat-1.png","width":1888,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/lgtbi-fobia-en-las-entidades-protocolos-para-combatirla\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Recursos igualdad y diversidad","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/recursos-igualdad\/"},{"@type":"ListItem","position":4,"name":"LGTBI-fobia en las entidades: protocolos para combatirla"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/0ff031aadbf63e105539f995878f9224","name":"oscar.loro","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/260a90b74d9872fae55664a1b14c1f343fa55f9884bce60c10a0fc4a1d0a53b7?s=96&d=monsterid&r=g","caption":"oscar.loro"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/oscar-loro\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/31551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/402"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=31551"}],"version-history":[{"count":12,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/31551\/revisions"}],"predecessor-version":[{"id":32051,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/31551\/revisions\/32051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/31542"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=31551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=31551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=31551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}