{"id":33649,"date":"2025-10-02T08:48:53","date_gmt":"2025-10-02T06:48:53","guid":{"rendered":"https:\/\/suport.fundesplai.org\/blog-es\/actualidad\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/"},"modified":"2025-11-05T16:17:34","modified_gmt":"2025-11-05T15:17:34","slug":"apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/","title":{"rendered":"Ap\u00fantate a la jornada: &#8216;El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?&#8217;"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>La financiaci\u00f3n p\u00fablica est\u00e1 cambiando, y las entidades del Tercer Sector estamos ante un reto crucial: <strong>adaptarnos o quedar atr\u00e1s<\/strong>. En este contexto, la jornada anual de <strong>Suport Tercer Sector<\/strong>, el pr\u00f3ximo <strong>24 de octubre,<\/strong> se convierte en un espacio imprescindible para entender las tendencias emergentes y explorar c\u00f3mo podemos reinventarnos ante los nuevos modelos de relaci\u00f3n con la Administraci\u00f3n. <\/p>\n<p>Durante la jornada, contaremos con <strong>ponencias inspiradoras<\/strong> de personas expertas y referentes del sector como <strong>Carles Campuzano,<\/strong> diputado del Parlament de Catalunya y exconsejero de Derechos Sociales del Govern de la Generalitat, <strong>Jessica Celd\u00e0<\/strong>, vicepresidenta de Mejora de la financiaci\u00f3n de la Taula del Tercer Sector Social y directora general de ECOM y <strong>Miquel de Paladel<\/strong> tendencias de la financiaci\u00f3n p\u00fablica y los retos actuales y futuros.<\/p>\n<h3>\ud83d\udca1 Un momento clave para entender hacia d\u00f3nde va la financiaci\u00f3n p\u00fablica<\/h3>\n<p>El Tercer Sector est\u00e1 en plena transformaci\u00f3n. El fin de los <g id=\"gid_0\">fondos Next Generation<\/g> , el impulso de las <g id=\"gid_1\">inversiones de impacto<\/g> y los cambios en las <g id=\"gid_2\">pol\u00edticas europeas<\/g> marcan un nuevo escenario. En Catalu\u00f1a, diversas normativas en tramitaci\u00f3n \u2014como la <strong>Ley de fomento del asociacionismo<\/strong>, la <strong>Ley del Tercer Sector Social<\/strong>, la <strong>Ley de econom\u00eda social y solidaria<\/strong> o la revisi\u00f3n de la <strong>cartera de servicios sociales\u2014<\/strong> afectar\u00e1n directamente a las entidades.  <\/p>\n<p>Adem\u00e1s, las administraciones p\u00fablicas est\u00e1n redefiniendo los modelos de <strong>subvenci\u00f3n<\/strong>, <strong>contrataci\u00f3n p\u00fablica<\/strong> y <strong>acci\u00f3n concertada<\/strong>, en un contexto que exige mayor <strong>transparencia<\/strong>, <strong>resultados<\/strong> y <strong>eficiencia<\/strong>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3 style=\"text-align: center;\">\u26a0\ufe0f Las plazas ya est\u00e1n completas y no aceptamos nuevas solicitudes. Si tienes confirmada la asistencia, \u00a1nos vemos el pr\u00f3ximo viernes 24 de octubre en el Palau Robert! Para cualquier aclaraci\u00f3n, puedes contactar con nosotros.  <\/h3>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/suport.fundesplai.org\/es\/contacta\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbCont\u00e1ctanos\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<h3><span class=\"EOP SCXW226600206 BCX8\">\ud83d\udc47 Programa de la jornada<\/span><\/h3>\n<p style=\"text-align: left;\"><strong>09.10 h | Acreditaci\u00f3n y desayuno de bienvenida<\/strong><\/p>\n<p style=\"text-align: left;\">\ud83e\udd32 Empezamos el d\u00eda con un espacio distendido para conectar con otros profesionales del sector mientras desayunamos juntas.<\/p>\n<p style=\"text-align: left;\"><strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">09.30 h | Presentaci\u00f3n de la jornada y nuevos retos<\/span><\/strong><\/p>\n<p style=\"text-align: left;\"><strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">09.45 h | Situaci\u00f3n general y tendencias en la financiaci\u00f3n p\u00fablica de las entidades del tercer sector<\/span><\/strong><\/p>\n<p style=\"text-align: left;\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udde3\ufe0f <strong>Carles Campuzano<\/strong> , diputado en el Parlament de Catalunya y exconsejero de Derechos Sociales del Gobierno de la Generalitat.<\/span><\/p>\n<p style=\"text-align: left;\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udccc Nos ofrecer\u00e1 una visi\u00f3n general sobre hacia d\u00f3nde va la financiaci\u00f3n p\u00fablica: subvenciones, contrataci\u00f3n p\u00fablica, acci\u00f3n concertada e inversiones de impacto. Adem\u00e1s, abordar\u00e1 las diferentes propuestas normativas que ya se han aprobado o que se encuentran en tr\u00e1mite. <\/span><\/p>\n<p style=\"text-align: left;\"><strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">10:30 h | Preocupaciones actuales en materia de financiaci\u00f3n p\u00fablica<\/span><\/strong><\/p>\n<p style=\"text-align: left;\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udde3\ufe0f <strong>J\u00e8ssica Celd\u00e0<\/strong>,<\/span> <span style=\"background-color: inherit;\">vicepresidenta<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">de Mejora de la financiaci\u00f3n de la Mesa del Tercer Sector Social y directora general de ECOM.<\/span><\/p>\n<p style=\"text-align: left;\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udccc Pondr\u00e1 sobre la mesa las preocupaciones m\u00e1s urgentes que afectan a las entidades: convocatorias, cartera de servicios, licitaciones\u2026 Adem\u00e1s, compartir\u00e1 los principales retos identificados por el grupo de trabajo de financiaci\u00f3n de la Mesa del Tercer Sector. <\/span><\/p>\n<p style=\"text-align: left;\"><strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">10:50 h | Retos y oportunidades de las inversiones de impacto<\/span><\/strong><\/p>\n<p style=\"text-align: left;\"><strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udde3\ufe0f<\/span><\/strong> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"><strong>Miquel de Paladella<\/strong> ,<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">CEO de UpSocial.<\/span><\/p>\n<p style=\"text-align: left;\"><strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">\ud83d\udccc<\/span><\/strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"> Descubriremos qu\u00e9 son las inversiones de impacto y c\u00f3mo pueden ser una potente herramienta para las administraciones p\u00fablicas y las entidades. Hablar\u00e1 de casos y tendencias en Europa y Espa\u00f1a, y c\u00f3mo aprovechar este instrumento todav\u00eda poco conocido. <\/span><\/p>\n<p style=\"text-align: left;\"><strong><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">11.15 h | Turno de preguntas y cierre<\/span><\/strong><\/p>\n<h3>\ud83d\udd0e Informaci\u00f3n pr\u00e1ctica<\/h3>\n<p>\ud83d\udcc5 24 de octubre de 2025<br \/> \ud83d\udd64 De 9 a 11.30 h<br \/> \ud83d\udccd Palau Robert <a href=\"https:\/\/www.google.com\/maps\/dir\/\/Pg.+de+Gr%C3%A0cia,+107,+L'Eixample,+08008+Barcelona\/@41.3960092,2.0770715,12z\/data=!4m8!4m7!1m0!1m5!1m1!1s0x12a4a296acbaa69b:0x94d9b1da92e3034c!2m2!1d2.1594723!2d41.3960386?entry=ttu&amp;g_ep=EgoyMDI1MDkyOS4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\">(Paseo de Gracia, 107 Barcelona)<\/a><br \/> \ud83c\udf9f\ufe0f Actividad gratuita con inscripci\u00f3n previa. Plazas limitadas.<br \/>\ud83d\udce9 infosuport@fundesplai.org \/ \u260e\ufe0f 93 474 74 50<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||30px||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>\ud83d\udccd \u00bfC\u00f3mo llegar?<\/h3>\n<p><a href=\"https:\/\/www.google.com\/maps\/dir\/\/Pg.+de+Gr%C3%A0cia,+107,+L'Eixample,+08008+Barcelona\/@41.3960092,2.0770715,12z\/data=!4m8!4m7!1m0!1m5!1m1!1s0x12a4a296acbaa69b:0x94d9b1da92e3034c!2m2!1d2.1594723!2d41.3960386?entry=ttu&amp;g_ep=EgoyMDI1MDkyOS4wIKXMDSoASAFQAw%3D%3D\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33554 alignleft\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/10\/Captura-de-pantalla-2025-10-01-110635.png\" alt=\"Palau Robert mapa\" width=\"373\" height=\"269\"><\/a>Recomendamos desplazarse al acto en el <a href=\"https:\/\/www.google.com\/maps\/dir\/\/Pg.+de+Gr%C3%A0cia,+107,+L'Eixample,+08008+Barcelona\/@41.3960092,2.0770715,12z\/data=!4m8!4m7!1m0!1m5!1m1!1s0x12a4a296acbaa69b:0x94d9b1da92e3034c!2m2!1d2.1594723!2d41.3960386?entry=ttu&amp;g_ep=EgoyMDI1MDkyOS4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noopener\"><strong>Palau Robert<\/strong><\/a> a pie o en transporte p\u00fablico para contribuir con la lucha del cambio clim\u00e1tico.<\/p>\n<p>\ud83d\ude87 <strong>Metro:<\/strong> Diagonal (L3 y L5).<\/p>\n<p>\ud83d\ude8c <strong>Autob\u00fas:<\/strong> 5, 7, 16, 17, 22, 24, 28, 33, 34 y 68.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_2,1_2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb|30px|||false|false\u00bb global_colors_info=\u00bb{}\u00bb]Organitza la Federaci\u00f3 Catalana de l&#8217;Esplai <img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16017\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2020\/10\/Federacio_sense_fons.png\" alt=\"\" width=\"574\" height=\"85\"> [\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_2&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: right;\">Col\u00b7labora l&#8217;Ajuntament de Barcelona<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-16019\" src=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2020\/10\/logo_bcn-800x270.png\" alt=\"\" width=\"252\" height=\"85\"> [\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_divider show_divider=\u00bboff\u00bb _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_divider _builder_version=\u00bb4.27.0&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>OTROS CONTENIDOS RELACIONADOS<\/strong><\/p>\n<ul>\n<li><a href=\"\/es\/?p=33400\">El certificado digital, una herramienta imprescindible para las entidades<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/actualidad\/el-govern-impulsa-una-reforma-del-plan-de-contabilidad-para-entidades-no-lucrativas\/\">El Govern impulsa una reforma del Plan de Contabilidad para entidades no lucrativas<\/a><\/li>\n<li><a href=\"\/es\/?p=33169\">9 Premios para financiar proyectos de educaci\u00f3n en el ocio<\/a><\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Descubre las nuevas tendencias en financiaci\u00f3n p\u00fablica para entidades del Tercer Sector en la jornada del 24 de octubre. Inscripci\u00f3n gratuita.  Plazas limitadas.<\/p>\n","protected":false},"author":377,"featured_media":33606,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[341,285],"tags":[],"class_list":["post-33649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","category-economico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ap\u00fantate a la jornada: &#039;El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?&#039; - Suport Tercer Sector - Fundesplai<\/title>\n<meta name=\"description\" content=\"Descubre las nuevas tendencias en financiaci\u00f3n p\u00fablica para entidades en la jornada del 24 de octubre. Inscripci\u00f3n gratuita. Plazas limitadas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ap\u00fantate a la jornada: &#039;El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?&#039; - Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Descubre las nuevas tendencias en financiaci\u00f3n p\u00fablica para entidades en la jornada del 24 de octubre. Inscripci\u00f3n gratuita. Plazas limitadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T06:48:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-05T15:17:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/10\/jornada-suport_2025.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Maria Eugenia Ifer Puntigliano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Eugenia Ifer Puntigliano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/\"},\"author\":{\"name\":\"Maria Eugenia Ifer Puntigliano\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/d67e880480b45b41df0ab5d2c3670fba\"},\"headline\":\"Ap\u00fantate a la jornada: &#8216;El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?&#8217;\",\"datePublished\":\"2025-10-02T06:48:53+00:00\",\"dateModified\":\"2025-11-05T15:17:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/\"},\"wordCount\":1020,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/jornada-suport_2025.jpg\",\"articleSection\":[\"Blog\",\"Econ\u00f3mico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/\",\"name\":\"Ap\u00fantate a la jornada: 'El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?' - Suport Tercer Sector - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/jornada-suport_2025.jpg\",\"datePublished\":\"2025-10-02T06:48:53+00:00\",\"dateModified\":\"2025-11-05T15:17:34+00:00\",\"description\":\"Descubre las nuevas tendencias en financiaci\u00f3n p\u00fablica para entidades en la jornada del 24 de octubre. Inscripci\u00f3n gratuita. Plazas limitadas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/jornada-suport_2025.jpg\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/jornada-suport_2025.jpg\",\"width\":1888,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Econ\u00f3mico\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/economico\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Ap\u00fantate a la jornada: &#8216;El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?&#8217;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/d67e880480b45b41df0ab5d2c3670fba\",\"name\":\"Maria Eugenia Ifer Puntigliano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g\",\"caption\":\"Maria Eugenia Ifer Puntigliano\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/meifer\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ap\u00fantate a la jornada: 'El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?' - Suport Tercer Sector - Fundesplai","description":"Descubre las nuevas tendencias en financiaci\u00f3n p\u00fablica para entidades en la jornada del 24 de octubre. Inscripci\u00f3n gratuita. Plazas limitadas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/","og_locale":"es_ES","og_type":"article","og_title":"Ap\u00fantate a la jornada: 'El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?' - Suport Tercer Sector - Fundesplai","og_description":"Descubre las nuevas tendencias en financiaci\u00f3n p\u00fablica para entidades en la jornada del 24 de octubre. Inscripci\u00f3n gratuita. Plazas limitadas.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2025-10-02T06:48:53+00:00","article_modified_time":"2025-11-05T15:17:34+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/10\/jornada-suport_2025.jpg","type":"image\/jpeg"}],"author":"Maria Eugenia Ifer Puntigliano","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"Maria Eugenia Ifer Puntigliano","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/"},"author":{"name":"Maria Eugenia Ifer Puntigliano","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/d67e880480b45b41df0ab5d2c3670fba"},"headline":"Ap\u00fantate a la jornada: &#8216;El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?&#8217;","datePublished":"2025-10-02T06:48:53+00:00","dateModified":"2025-11-05T15:17:34+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/"},"wordCount":1020,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/10\/jornada-suport_2025.jpg","articleSection":["Blog","Econ\u00f3mico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/","name":"Ap\u00fantate a la jornada: 'El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?' - Suport Tercer Sector - Fundesplai","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/10\/jornada-suport_2025.jpg","datePublished":"2025-10-02T06:48:53+00:00","dateModified":"2025-11-05T15:17:34+00:00","description":"Descubre las nuevas tendencias en financiaci\u00f3n p\u00fablica para entidades en la jornada del 24 de octubre. Inscripci\u00f3n gratuita. Plazas limitadas.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/10\/jornada-suport_2025.jpg","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2025\/10\/jornada-suport_2025.jpg","width":1888,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/apuntate-a-la-jornada-el-futuro-de-la-financiacion-publica-en-el-tercer-sector-sobrevivir-o-reinventarnos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Econ\u00f3mico","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/economico\/"},{"@type":"ListItem","position":4,"name":"Ap\u00fantate a la jornada: &#8216;El futuro de la financiaci\u00f3n p\u00fablica en el Tercer Sector: \u00bfsobrevivir o reinventarnos?&#8217;"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/d67e880480b45b41df0ab5d2c3670fba","name":"Maria Eugenia Ifer Puntigliano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d6f452030d1e5d988a270d205fbc06489eac700fb463d9abd26f76d07f8fa0d8?s=96&d=monsterid&r=g","caption":"Maria Eugenia Ifer Puntigliano"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/meifer\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/33649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/377"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=33649"}],"version-history":[{"count":20,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/33649\/revisions"}],"predecessor-version":[{"id":34120,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/33649\/revisions\/34120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/33606"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=33649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=33649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=33649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}