{"id":35137,"date":"2026-02-26T11:18:15","date_gmt":"2026-02-26T10:18:15","guid":{"rendered":"https:\/\/suport.fundesplai.org\/?p=35137"},"modified":"2026-03-24T11:24:11","modified_gmt":"2026-03-24T10:24:11","slug":"todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/","title":{"rendered":"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_padding=\u00bb|||1px||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>La Administraci\u00f3n p\u00fablica ha publicado el <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2026-3815\" target=\"_blank\" rel=\"noopener\"><strong>Real Decreto 126\/2026,<\/strong> de<\/a> <a href=\"https:\/\/www.boe.es\/buscar\/act.php?id=BOE-A-2026-3815\" target=\"_blank\" rel=\"noopener\">18 de febrero de 2026 en el Bolet\u00edn Oficial del Estado (BOE)<\/a> con el que queda establecido el nuevo Salario M\u00ednimo Interprofesional (SMI) del a\u00f1o 2026. El <strong>SMI es la retribuci\u00f3n m\u00ednima<\/strong> que, por ley, debe recibir cualquier persona. <\/p>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/suport.fundesplai.org\/es\/servicios\/laboral\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bb\u00a1Contacta con nosotros!\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_text _builder_version=\u00bb4.27.5&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>El Consejo de Ministros ha aprobado un incremento del <strong>3,1%<\/strong> del salario m\u00ednimo interprofesional ( <strong>SMI<\/strong> ), que se sit\u00faa en <strong>1.221 euros brutos mensuales<\/strong> en catorce pagas. La medida, publicada el 18 de febrero de 2026 en el Bolet\u00edn Oficial del Estado (BOE) mediante el <strong>Real Decreto 126\/2026<\/strong> , tiene efectos retroactivos desde el <strong>1 de enero de 2026<\/strong> y repercute directamente en casi dos millones de personas asalariadas en el Estado. <\/p>\n<p>En c\u00f3mputo anual, el salario m\u00ednimo queda fijado en <strong>17.094 euros brutos anuales<\/strong> , mientras que en doce pagas asciende a <strong>1.424,5 euros mensuales<\/strong> . El incremento representa aproximadamente 43 euros m\u00e1s al mes para las personas que perciben ese sueldo. <\/p>\n<h3><strong>Impacto en el conjunto de personas trabajadoras<\/strong><\/h3>\n<p>Seg\u00fan los datos recogidos, la revisi\u00f3n al alza afecta especialmente a sectores con salarios m\u00e1s bajos y con una presencia elevada de mujeres y personas j\u00f3venes. El SMI act\u00faa como <strong>referencia m\u00ednima legal<\/strong> para todas las relaciones laborales e incide tambi\u00e9n en determinadas prestaciones y contratos vinculados a esa cuant\u00eda. <\/p>\n<p>Desde 2018, el salario m\u00ednimo ha experimentado diversos incrementos consecutivos. Con esta nueva actualizaci\u00f3n, el Gobierno mantiene el objetivo de adecuar el salario m\u00ednimo a la evoluci\u00f3n del coste de la vida y los compromisos adquiridos en materia de derechos laborales. <\/p>\n<h3><strong>Repercusi\u00f3n en el tercer sector<\/strong><\/h3>\n<p>El aumento del SMI tambi\u00e9n tiene implicaciones directas para las <strong>entidades del tercer sector<\/strong> , especialmente aquellas que gestionan servicios con personal contratado en categor\u00edas cercanas al salario m\u00ednimo. Las organizaciones tendr\u00e1n que adaptar sus <strong>tablas salariales<\/strong> y previsiones presupuestarias para garantizar el cumplimiento de la nueva cuant\u00eda. <\/p>\n<p>Asimismo, la medida puede contribuir a <strong>mejorar las condiciones de vida<\/strong> de personas trabajadoras vinculadas a proyectos sociales, muchas de las cuales desarrollan labores de atenci\u00f3n directa en \u00e1mbitos como la acci\u00f3n social, la educaci\u00f3n en el ocio o la inserci\u00f3n laboral.<\/p>\n<p>[\/et_pb_text][et_pb_divider _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3>OTROS CONTENIDOS:<\/h3>\n<ul>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/laboral-es\/las-organizaciones-no-pueden-despedir-sin-escuchar-a-la-persona-trabajadora\/\">Las organizaciones no pueden despedir sin escuchar a la persona trabajadora<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/laboral-es\/como-encontrar-talento-en-las-redes-sociales\/\" target=\"_blank\" rel=\"noopener\">\u00bfC\u00f3mo encontrar talento en las redes sociales?<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/laboral-es\/manual-de-contratacion-de-personas-becarias\/\" target=\"_blank\" rel=\"noopener\">Manual de contrataci\u00f3n de personas becarias<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/actualidad\/la-persona-de-referencia-clave-para-un-espacio-laboral-seguro-frente-al-acoso\/\">La persona de referencia: clave para un espacio laboral seguro frente al acoso<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/laboral-es\/aumento-de-las-jornadas-laborales-como-se-regula\/\">Aumento de las jornadas laborales: \u00bfc\u00f3mo se regula?<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Administraci\u00f3n p\u00fablica ha publicado el Real decreto 126\/2026 donde queda establecido el nuevo Salario M\u00ednimo Interprofesional del a\u00f1o 2026.<\/p>\n","protected":false},"author":416,"featured_media":35144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[341],"tags":[],"class_list":["post-35137","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026 - Suport Tercer Sector - Fundesplai<\/title>\n<meta name=\"description\" content=\"La Administraci\u00f3n p\u00fablica ha publicado el Real decreto 126\/2026 donde queda establecido el nuevo Salario M\u00ednimo Interprofesional del a\u00f1o 2026.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026 - Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"La Administraci\u00f3n p\u00fablica ha publicado el Real decreto 126\/2026 donde queda establecido el nuevo Salario M\u00ednimo Interprofesional del a\u00f1o 2026.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-26T10:18:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T10:24:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/02\/SMI-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aina.galceran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aina.galceran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/\"},\"author\":{\"name\":\"aina.galceran\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/2902d6069eec22bcad2830df54b34376\"},\"headline\":\"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026\",\"datePublished\":\"2026-02-26T10:18:15+00:00\",\"dateModified\":\"2026-03-24T10:24:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/\"},\"wordCount\":613,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/SMI-1.jpg\",\"articleSection\":[\"Blog\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/\",\"name\":\"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026 - Suport Tercer Sector - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/SMI-1.jpg\",\"datePublished\":\"2026-02-26T10:18:15+00:00\",\"dateModified\":\"2026-03-24T10:24:11+00:00\",\"description\":\"La Administraci\u00f3n p\u00fablica ha publicado el Real decreto 126\\\/2026 donde queda establecido el nuevo Salario M\u00ednimo Interprofesional del a\u00f1o 2026.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/SMI-1.jpg\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/SMI-1.jpg\",\"width\":1888,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/2902d6069eec22bcad2830df54b34376\",\"name\":\"aina.galceran\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g\",\"caption\":\"aina.galceran\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/aina-galceran\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026 - Suport Tercer Sector - Fundesplai","description":"La Administraci\u00f3n p\u00fablica ha publicado el Real decreto 126\/2026 donde queda establecido el nuevo Salario M\u00ednimo Interprofesional del a\u00f1o 2026.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/","og_locale":"es_ES","og_type":"article","og_title":"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026 - Suport Tercer Sector - Fundesplai","og_description":"La Administraci\u00f3n p\u00fablica ha publicado el Real decreto 126\/2026 donde queda establecido el nuevo Salario M\u00ednimo Interprofesional del a\u00f1o 2026.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2026-02-26T10:18:15+00:00","article_modified_time":"2026-03-24T10:24:11+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/02\/SMI-1.jpg","type":"image\/jpeg"}],"author":"aina.galceran","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"aina.galceran","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/"},"author":{"name":"aina.galceran","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/2902d6069eec22bcad2830df54b34376"},"headline":"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026","datePublished":"2026-02-26T10:18:15+00:00","dateModified":"2026-03-24T10:24:11+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/"},"wordCount":613,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/02\/SMI-1.jpg","articleSection":["Blog"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/","name":"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026 - Suport Tercer Sector - Fundesplai","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/02\/SMI-1.jpg","datePublished":"2026-02-26T10:18:15+00:00","dateModified":"2026-03-24T10:24:11+00:00","description":"La Administraci\u00f3n p\u00fablica ha publicado el Real decreto 126\/2026 donde queda establecido el nuevo Salario M\u00ednimo Interprofesional del a\u00f1o 2026.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/02\/SMI-1.jpg","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/02\/SMI-1.jpg","width":1888,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/todo-lo-que-hay-que-saber-sobre-el-salario-minimo-interprofesional-para-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Todo lo que hay que saber sobre el Salario M\u00ednimo Interprofesional para 2026"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/2902d6069eec22bcad2830df54b34376","name":"aina.galceran","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g","caption":"aina.galceran"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/aina-galceran\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/35137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/416"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=35137"}],"version-history":[{"count":6,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/35137\/revisions"}],"predecessor-version":[{"id":35440,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/35137\/revisions\/35440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/35144"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=35137"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=35137"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=35137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}