{"id":37255,"date":"2026-08-17T09:49:57","date_gmt":"2026-08-17T07:49:57","guid":{"rendered":"https:\/\/suport.fundesplai.org\/?p=37255"},"modified":"2026-08-27T09:51:48","modified_gmt":"2026-08-27T07:51:48","slug":"como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/","title":{"rendered":"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n?"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.16&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"block block-field_resource_summary\">\n<div class=\"qMYqUG_convSearchResultHighlightRoot\">\n<div class=\"\" data-turn-id-container=\"request-6a465556-bbb8-83eb-a377-90d275bdadd4-4\" data-is-intersecting=\"true\">\n<section class=\"text-token-text-primary w-full focus:outline-none has-data-writing-block:pointer-events-none [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto R6Vx5W_threadScrollVars scroll-mb-[calc(var(--scroll-root-safe-area-inset-bottom,0px)+var(--thread-response-height))] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" data-turn-id=\"request-6a465556-bbb8-83eb-a377-90d275bdadd4-4\" data-turn-id-container=\"request-6a465556-bbb8-83eb-a377-90d275bdadd4-4\" data-testid=\"conversation-turn-10\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" data-conversation-screenshot-content=\"\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal outline-none keyboard-focused:focus-ring [.text-message+&amp;]:mt-1\" dir=\"auto\" tabindex=\"0\" data-message-author-role=\"assistant\" data-message-id=\"32c78e77-cdf2-48ac-9a84-81de4ecead8b\" data-message-model-slug=\"gpt-5-5-thinking\" data-turn-start-message=\"true\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert wrap-break-word w-full light markdown-new-styling\">\n<p class=\"PDq2pG_selectionAnchorContainer\" data-start=\"0\" data-end=\"198\" data-is-last-node=\"\" data-is-only-node=\"\">Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la <strong>sustituci\u00f3n<\/strong> o la <strong>incorporaci\u00f3n de miembros<\/strong> . En caso de dudas puedes contactar con nuestro <a href=\"https:\/\/suport.fundesplai.org\/es\/servicios\/juridico\/\" target=\"_blank\" rel=\"noopener\">servicio jur\u00eddico<\/a> . <\/p>\n<p class=\"isSelectedEnd\">Las asociaciones deben contar con una <strong>junta directiva<\/strong> formada, como m\u00ednimo, por <strong>tres miembros<\/strong> . La presidencia y la secretar\u00eda son dos cargos obligatorios. Tal y como establece la Ley 4\/2008, \u201cla duraci\u00f3n del cargo de miembro del \u00f3rgano de gobierno no puede exceder de cinco a\u00f1os, sin perjuicio del derecho a la reelecci\u00f3n si no la excluyen los estatutos\u201d.  <\/p>\n<p class=\"isSelectedEnd\">Sin embargo, a veces se pueden producir cambios en la junta, ya sea por la sustituci\u00f3n de miembros o por nuevas incorporaciones.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_button button_url=\u00bbhttps:\/\/suport.fundesplai.org\/es\/servicios\/juridico\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbContacta con el servicio jur\u00eddico\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][et_pb_code _builder_version=\u00bb4.27.7&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_code][et_pb_text _builder_version=\u00bb4.27.6&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb custom_margin=\u00bb30px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"block block-field_tags\">\n<div class=\"content\">\n<div class=\"field-tags field-type-entity-reference field-label-inline\">\n<div class=\"block block-body\">\n<div class=\"content\">\n<div class=\"field-body field-type-text-with-summary field-label-hidden field-value\">\n<section data-history-node-id=\"84794\">\n<div class=\"field-body field-type-text-with-summary field-label-hidden field-value\">\n<section data-history-node-id=\"147642\">\n<div class=\"field-body field-type-text-with-summary field-label-hidden field-value\">\n<section data-history-node-id=\"85612\">\n<div class=\"field-body field-type-text-with-summary field-label-hidden field-value\">\n<div class=\"block block-body\">\n<div class=\"content\">\n<div class=\"block block-body\">\n<div class=\"content\">\n<div class=\"field-body field-type-text-with-summary field-label-hidden field-value\">\n<section data-history-node-id=\"85612\">\n<div class=\"field-body field-type-text-with-summary field-label-hidden field-value\">\n<div class=\"block block-body\">\n<div class=\"content\">\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Taula de continguts<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #525459;color:#525459\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #525459;color:#525459\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#%C2%BFQuien_puede_formar_parte_de_la_junta\" >\u00bfQui\u00e9n puede formar parte de la junta?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#%C2%BFCual_es_el_primer_paso_para_incorporar_a_nuevas_personas\" >\u00bfCu\u00e1l es el primer paso para incorporar a nuevas personas?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#%C2%BFEs_necesario_modificar_los_estatutos_de_la_asociacion\" >\u00bfEs necesario modificar los estatutos de la asociaci\u00f3n?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#%C2%BFComo_realizar_un_buen_traspaso_a_las_nuevas_incorporaciones\" >\u00bfC\u00f3mo realizar un buen traspaso a las nuevas incorporaciones?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#Otros_contenidos_relacionados\" >Otros contenidos relacionados:<\/a><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFQuien_puede_formar_parte_de_la_junta\"><\/span>\u00bfQui\u00e9n puede formar parte de la junta?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"isSelectedEnd\">Para formar parte de la junta directiva de una asociaci\u00f3n es necesario ser <strong>persona socia<\/strong> , <strong>mayor de edad<\/strong> y no tener ninguna inhabilitaci\u00f3n de acuerdo con la <strong>legislaci\u00f3n concursal<\/strong> , en el caso de las entidades que desarrollan una actividad econ\u00f3mica.<\/p>\n<p class=\"isSelectedEnd\">Las personas asociadas escogen a los miembros de la junta mediante una <strong>votaci\u00f3n en asamblea<\/strong> oa trav\u00e9s del procedimiento electoral que establezcan los estatutos de la asociaci\u00f3n.<\/p>\n<p class=\"isSelectedEnd\">Los miembros de este \u00f3rgano de gobierno deben asistir a las reuniones, informarse sobre la actividad de la asociaci\u00f3n y participar en la <strong>toma de decisiones<\/strong> . Adem\u00e1s, la junta se encarga de custodiar y actualizar los <strong>libros de la entidad<\/strong> , como el libro de actas, el libro de personas socias o los libros de contabilidad, y debe preservar la <strong>confidencialidad de la informaci\u00f3n<\/strong> de la asociaci\u00f3n. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFCual_es_el_primer_paso_para_incorporar_a_nuevas_personas\"><\/span>\u00bfCu\u00e1l es el primer paso para incorporar a nuevas personas?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"isSelectedEnd\">La junta directiva puede incorporar nuevas personas al \u00f3rgano de gobierno para <strong>cubrir las vacantes<\/strong> . En este caso, puede nombrar <strong>a personas sustitutas<\/strong> , que pueden ocupar el cargo hasta la siguiente asamblea general o hasta la elecci\u00f3n de nuevos cargos, seg\u00fan lo que establezcan los estatutos. <\/p>\n<p class=\"isSelectedEnd\">Para que la incorporaci\u00f3n sea definitiva, la <strong>asamblea general<\/strong> , ordinaria o extraordinaria, seg\u00fan establezcan los estatutos, debe <strong>ratificar el nombramiento<\/strong> mediante la votaci\u00f3n correspondiente. Una vez ratificada la incorporaci\u00f3n, las personas designadas deben <strong>aceptar el cargo<\/strong> para el que han sido escogidas mediante la firma del acta de la asamblea. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFEs_necesario_modificar_los_estatutos_de_la_asociacion\"><\/span>\u00bfEs necesario modificar los estatutos de la asociaci\u00f3n?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"isSelectedEnd\">Los estatutos de cada entidad determinan la <strong>composici\u00f3n de la junta directiva<\/strong> . Tal como indica la Ley 4\/2008, deben regular \u201clas reglas sobre la organizaci\u00f3n y el funcionamiento del \u00f3rgano de gobierno que establezcan el r\u00e9gimen de convocatoria y constituci\u00f3n, la composici\u00f3n, la forma de designar, destituir y renovar a sus miembros, y la duraci\u00f3n del mandato de \u00e9stos\u201d. <\/p>\n<p class=\"isSelectedEnd\">Si la incorporaci\u00f3n comporta un cambio en la composici\u00f3n de la junta o en los cargos establecidos en los estatutos, es necesario <strong>modificar los estatutos<\/strong> y aprobar la modificaci\u00f3n en <strong>asamblea general<\/strong> .<\/p>\n<p class=\"isSelectedEnd\">En todos los casos, debe presentarse en el <strong>Registro de Asociaciones<\/strong> un certificado conforme con el acta de la asamblea en el que conste la nueva composici\u00f3n de la junta directiva. Este documento debe estar firmado por las personas que ocupan la presidencia y la secretar\u00eda, tanto entrantes como salientes. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFComo_realizar_un_buen_traspaso_a_las_nuevas_incorporaciones\"><\/span>\u00bfC\u00f3mo realizar un buen traspaso a las nuevas incorporaciones?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p class=\"isSelectedEnd\">El <strong>traspaso de las competencias<\/strong> a las personas que se incorporen al \u00f3rgano de gobierno depender\u00e1 del cargo y de la propia organizaci\u00f3n de la asociaci\u00f3n.<\/p>\n<p class=\"isSelectedEnd\">Todas las personas que forman parte de la junta comparten unas <strong>responsabilidades<\/strong> y deberes hacia la entidad. Por este motivo, deben conocer su situaci\u00f3n en todos los \u00e1mbitos: las actas de las reuniones de la junta y de las asambleas, el libro de personas socias, los libros de contabilidad y el estado de las cuentas, entre otras cuestiones. <\/p>\n<p class=\"isSelectedEnd\">Seg\u00fan el cargo que asuma cada miembro, tendr\u00e1 unas responsabilidades m\u00e1s espec\u00edficas, lo que requerir\u00e1 prestar mayor atenci\u00f3n a determinados aspectos y documentos.<\/p>\n<p class=\"isSelectedEnd\">Si una persona asume la <strong>tesorer\u00eda<\/strong> , es importante traspasarle toda la documentaci\u00f3n relativa a la contabilidad de la entidad o facilitarle el contacto con la gestor\u00eda que se encarga de las cuentas.<\/p>\n<p class=\"isSelectedEnd\">En caso de que el nuevo cargo sea una <strong>vocal\u00eda<\/strong> , es oportuno poner especial \u00e9nfasis en el traspaso del libro de actas para que la persona se pueda poner al d\u00eda de la actividad de la entidad.<\/p>\n<p class=\"isSelectedEnd\">Cuando las nuevas incorporaciones asumen la <strong>presidencia<\/strong> o la <strong>secretar\u00eda<\/strong> , adem\u00e1s del libro de actas, es necesario traspasar con especial atenci\u00f3n el libro de personas socias, el libro de voluntariado y toda la documentaci\u00f3n con la que trabaja la junta.<\/p>\n<p>Para realizar un buen traspaso tambi\u00e9n es importante dejar toda la <strong>documentaci\u00f3n actualizada<\/strong> y ordenada, as\u00ed como las actas debidamente firmadas. El proceso debe llevarse a cabo correctamente para facilitar la gesti\u00f3n y contribuir al <strong>buen funcionamiento de la entidad<\/strong> . <\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<p>Fuente: redactado por el equip de Suport Tercer Sector <a href=\"https:\/\/xarxanet.org\/juridic\/recursos\/que-han-de-saber-les-entitats-socials-abans-de-presentar-se-una-licitacio-publica\">en Xarxanet<\/a><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/section>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][et_pb_divider _builder_version=\u00bb4.24.3&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb20px||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_divider][et_pb_text _builder_version=\u00bb4.27.6&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Otros_contenidos_relacionados\"><\/span>Otros contenidos relacionados:<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/barcelona-impulsa-un-espacio-estable-de-dialogo-con-el-tercer-sector-social\/\">Barcelona impulsa un espacio estable de di\u00e1logo con el tercer sector social<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/se-aprueba-el-iv-plan-nacional-del-asociacionismo-y-el-voluntariado-2026-2029\/\">Se aprueba el IV Plan nacional del asociacionismo y el voluntariado 2026-2029<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/blog\/juridic\/guia-per-obtenir-el-certificat-digital-duna-entitat-religiosa-pas-a-pas\/?preview=true\">Aumenta el control sobre los despidos previos a la jubilaci\u00f3n<\/a><\/li>\n<li><a href=\"https:\/\/suport.fundesplai.org\/blog\/juridic\/quan-i-com-comunicar-el-nomenament-del-responsable-del-sistema-intern-dinformacio\/\">El nombramiento del responsable del sistema interno de informaci\u00f3n: plazos y pasos a seguir<\/a><\/li>\n<li class=\"entry-title\"><a href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/la-planificacion-anual-una-obligacion-estrategica-para-el-buen-gobierno-de-las-entidades\/\">La planificaci\u00f3n anual, una obligaci\u00f3n estrat\u00e9gica para el buen gobierno de las entidades<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la sustituci\u00f3n o incorporaci\u00f3n de miembros.<\/p>\n","protected":false},"author":416,"featured_media":37261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[275],"tags":[],"class_list":["post-37255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juridico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n? - Suport Tercer Sector - Fundesplai<\/title>\n<meta name=\"description\" content=\"Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la sustituci\u00f3n o incorporaci\u00f3n de miembros.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n? - Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la sustituci\u00f3n o incorporaci\u00f3n de miembros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-08-17T07:49:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-27T07:51:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/07\/abans-de-tancar-el-curs.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1888\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"aina.galceran\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aina.galceran\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/\"},\"author\":{\"name\":\"aina.galceran\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/2902d6069eec22bcad2830df54b34376\"},\"headline\":\"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n?\",\"datePublished\":\"2026-08-17T07:49:57+00:00\",\"dateModified\":\"2026-08-27T07:51:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/\"},\"wordCount\":1123,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/abans-de-tancar-el-curs.png\",\"articleSection\":[\"Jur\u00eddico\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/\",\"name\":\"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n? - Suport Tercer Sector - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/abans-de-tancar-el-curs.png\",\"datePublished\":\"2026-08-17T07:49:57+00:00\",\"dateModified\":\"2026-08-27T07:51:48+00:00\",\"description\":\"Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la sustituci\u00f3n o incorporaci\u00f3n de miembros.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/abans-de-tancar-el-curs.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/abans-de-tancar-el-curs.png\",\"width\":1888,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jur\u00eddico\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/blog-es\\\/juridico\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/2902d6069eec22bcad2830df54b34376\",\"name\":\"aina.galceran\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g\",\"caption\":\"aina.galceran\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/aina-galceran\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n? - Suport Tercer Sector - Fundesplai","description":"Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la sustituci\u00f3n o incorporaci\u00f3n de miembros.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n? - Suport Tercer Sector - Fundesplai","og_description":"Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la sustituci\u00f3n o incorporaci\u00f3n de miembros.","og_url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2026-08-17T07:49:57+00:00","article_modified_time":"2026-08-27T07:51:48+00:00","og_image":[{"width":1888,"height":900,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/07\/abans-de-tancar-el-curs.png","type":"image\/png"}],"author":"aina.galceran","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"aina.galceran","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/"},"author":{"name":"aina.galceran","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/2902d6069eec22bcad2830df54b34376"},"headline":"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n?","datePublished":"2026-08-17T07:49:57+00:00","dateModified":"2026-08-27T07:51:48+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/"},"wordCount":1123,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/07\/abans-de-tancar-el-curs.png","articleSection":["Jur\u00eddico"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/","url":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/","name":"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n? - Suport Tercer Sector - Fundesplai","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/07\/abans-de-tancar-el-curs.png","datePublished":"2026-08-17T07:49:57+00:00","dateModified":"2026-08-27T07:51:48+00:00","description":"Los \u00f3rganos de gobierno de las entidades pueden modificar su composici\u00f3n con la sustituci\u00f3n o incorporaci\u00f3n de miembros.","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/07\/abans-de-tancar-el-curs.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2026\/07\/abans-de-tancar-el-curs.png","width":1888,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/como-incorporar-o-sustituir-a-miembros-de-la-junta-directiva-de-una-asociacion-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"Blog","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/"},{"@type":"ListItem","position":3,"name":"Jur\u00eddico","item":"https:\/\/suport.fundesplai.org\/es\/blog-es\/juridico\/"},{"@type":"ListItem","position":4,"name":"\u00bfC\u00f3mo incorporar o sustituir a miembros de la junta directiva de una asociaci\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/2902d6069eec22bcad2830df54b34376","name":"aina.galceran","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85207edde0725a27fe22372aca83128037136e9f5d656afa91335eca14c0a5d3?s=96&d=monsterid&r=g","caption":"aina.galceran"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/aina-galceran\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/37255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/416"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=37255"}],"version-history":[{"count":2,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/37255\/revisions"}],"predecessor-version":[{"id":37442,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/37255\/revisions\/37442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/37261"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=37255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=37255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=37255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}