{"id":8396,"date":"2019-08-08T07:42:14","date_gmt":"2019-08-08T06:42:14","guid":{"rendered":"https:\/\/suport.fundesplai.org\/actualidad\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/"},"modified":"2019-08-09T08:48:00","modified_gmt":"2019-08-09T07:48:00","slug":"cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal","status":"publish","type":"post","link":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/","title":{"rendered":"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal?"},"content":{"rendered":"<p>No hay diferencia con respecto a la contrataci\u00f3n de una organizaci\u00f3n sin fines de lucro o una empresa. Los procesos son los mismos:<\/p>\n<p>1. Alta de entidad en la Seguridad Social.<br \/>\n2. Inscripci\u00f3n del empleado en la Seguridad Social.<br \/>\n3. Confecci\u00f3n del contrato de trabajo.<br \/>\n4. Registro del contrato en la SEPE (www.sepe.es)<br \/>\n5. Precio de la acci\u00f3n e impuestos.<\/p>\n<p>Lo que suelen olvidar de la entidad es objeto de la prevenci\u00f3n de riesgos laborales. Con respecto a esto, cualquier empresa, entidad o fundaci\u00f3n, incluso si es sin fines de lucro, que tenga personal contratado debe cumplir con la Ley 31\/1995 de Prevenci\u00f3n de Riesgos Laborales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No hay diferencia con respecto a la contrataci\u00f3n de una organizaci\u00f3n sin fines de lucro o una empresa. Los procesos son los mismos: 1. Alta de entidad en la Seguridad Social. 2. Inscripci\u00f3n del empleado en la Seguridad Social. 3. Confecci\u00f3n del contrato de trabajo. 4. Registro del contrato en la SEPE (www.sepe.es) 5. Precio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7991,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[272,274],"tags":[],"class_list":["post-8396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faqs-es","category-faqs-laboral-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal? - Suport Tercer Sector - Fundesplai<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal? - Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"og:description\" content=\"No hay diferencia con respecto a la contrataci\u00f3n de una organizaci\u00f3n sin fines de lucro o una empresa. Los procesos son los mismos: 1. Alta de entidad en la Seguridad Social. 2. Inscripci\u00f3n del empleado en la Seguridad Social. 3. Confecci\u00f3n del contrato de trabajo. 4. Registro del contrato en la SEPE (www.sepe.es) 5. Precio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/\" \/>\n<meta property=\"og:site_name\" content=\"Suport Tercer Sector - Fundesplai\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Fundesplai\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-08T06:42:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-09T07:48:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/01\/empreses-associacions.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1152\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"marubio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@suport_org\" \/>\n<meta name=\"twitter:site\" content=\"@suport_org\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"marubio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/\"},\"author\":{\"name\":\"marubio\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/298d966724e84c57901bc05c8d161915\"},\"headline\":\"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal?\",\"datePublished\":\"2019-08-08T06:42:14+00:00\",\"dateModified\":\"2019-08-09T07:48:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/\"},\"wordCount\":128,\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/empreses-associacions.jpg\",\"articleSection\":[\"FAQs\",\"FAQs Laboral\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/\",\"name\":\"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal? - Suport Tercer Sector - Fundesplai\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/empreses-associacions.jpg\",\"datePublished\":\"2019-08-08T06:42:14+00:00\",\"dateModified\":\"2019-08-09T07:48:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/empreses-associacions.jpg\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/empreses-associacions.jpg\",\"width\":1152,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQs\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FAQs Laboral\",\"item\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/faqs-es\\\/faqs-laboral-es\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"name\":\"Suport Tercer Sector - Fundesplai\",\"description\":\"Gesti\u00f3n de asociaciones y fundaciones\",\"publisher\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#organization\",\"name\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"contentUrl\":\"https:\\\/\\\/suport.fundesplai.org\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/lgo-suport-tercer-sector-fe-2.png\",\"width\":300,\"height\":141,\"caption\":\"Suport Tercer Sector de Fundesplai per entitats i associacions\"},\"image\":{\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Fundesplai\\\/\",\"https:\\\/\\\/x.com\\\/suport_org\",\"https:\\\/\\\/www.instagram.com\\\/fundesplai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fundesplai\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCGaevIfQeecUHeWq1m-WLYw\",\"https:\\\/\\\/ca.wikipedia.org\\\/wiki\\\/Fundaci\u00f3_Catalana_de_l'Esplai\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/#\\\/schema\\\/person\\\/298d966724e84c57901bc05c8d161915\",\"name\":\"marubio\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=monsterid&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=monsterid&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=monsterid&r=g\",\"caption\":\"marubio\"},\"url\":\"https:\\\/\\\/suport.fundesplai.org\\\/es\\\/author\\\/marubio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal? - Suport Tercer Sector - Fundesplai","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal? - Suport Tercer Sector - Fundesplai","og_description":"No hay diferencia con respecto a la contrataci\u00f3n de una organizaci\u00f3n sin fines de lucro o una empresa. Los procesos son los mismos: 1. Alta de entidad en la Seguridad Social. 2. Inscripci\u00f3n del empleado en la Seguridad Social. 3. Confecci\u00f3n del contrato de trabajo. 4. Registro del contrato en la SEPE (www.sepe.es) 5. Precio [&hellip;]","og_url":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/","og_site_name":"Suport Tercer Sector - Fundesplai","article_publisher":"https:\/\/www.facebook.com\/Fundesplai\/","article_published_time":"2019-08-08T06:42:14+00:00","article_modified_time":"2019-08-09T07:48:00+00:00","og_image":[{"width":1152,"height":768,"url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/01\/empreses-associacions.jpg","type":"image\/jpeg"}],"author":"marubio","twitter_card":"summary_large_image","twitter_creator":"@suport_org","twitter_site":"@suport_org","twitter_misc":{"Escrito por":"marubio","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/#article","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/"},"author":{"name":"marubio","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/298d966724e84c57901bc05c8d161915"},"headline":"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal?","datePublished":"2019-08-08T06:42:14+00:00","dateModified":"2019-08-09T07:48:00+00:00","mainEntityOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/"},"wordCount":128,"publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/01\/empreses-associacions.jpg","articleSection":["FAQs","FAQs Laboral"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/","url":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/","name":"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal? - Suport Tercer Sector - Fundesplai","isPartOf":{"@id":"https:\/\/suport.fundesplai.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/#primaryimage"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/#primaryimage"},"thumbnailUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/01\/empreses-associacions.jpg","datePublished":"2019-08-08T06:42:14+00:00","dateModified":"2019-08-09T07:48:00+00:00","breadcrumb":{"@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/#primaryimage","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/01\/empreses-associacions.jpg","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/01\/empreses-associacions.jpg","width":1152,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/cuales-son-las-diferencias-entre-una-entidad-en-comparacion-con-una-empresa-comercial-al-contratar-a-un-personal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/suport.fundesplai.org\/es\/"},{"@type":"ListItem","position":2,"name":"FAQs","item":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/"},{"@type":"ListItem","position":3,"name":"FAQs Laboral","item":"https:\/\/suport.fundesplai.org\/es\/faqs-es\/faqs-laboral-es\/"},{"@type":"ListItem","position":4,"name":"\u00bfCu\u00e1les son las diferencias entre una entidad en comparaci\u00f3n con una empresa comercial al contratar personal?"}]},{"@type":"WebSite","@id":"https:\/\/suport.fundesplai.org\/es\/#website","url":"https:\/\/suport.fundesplai.org\/es\/","name":"Suport Tercer Sector - Fundesplai","description":"Gesti\u00f3n de asociaciones y fundaciones","publisher":{"@id":"https:\/\/suport.fundesplai.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/suport.fundesplai.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/suport.fundesplai.org\/es\/#organization","name":"Suport Tercer Sector de Fundesplai per entitats i associacions","url":"https:\/\/suport.fundesplai.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","contentUrl":"https:\/\/suport.fundesplai.org\/wp-content\/uploads\/2019\/08\/lgo-suport-tercer-sector-fe-2.png","width":300,"height":141,"caption":"Suport Tercer Sector de Fundesplai per entitats i associacions"},"image":{"@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Fundesplai\/","https:\/\/x.com\/suport_org","https:\/\/www.instagram.com\/fundesplai\/","https:\/\/www.linkedin.com\/company\/fundesplai","https:\/\/www.youtube.com\/channel\/UCGaevIfQeecUHeWq1m-WLYw","https:\/\/ca.wikipedia.org\/wiki\/Fundaci\u00f3_Catalana_de_l'Esplai"]},{"@type":"Person","@id":"https:\/\/suport.fundesplai.org\/es\/#\/schema\/person\/298d966724e84c57901bc05c8d161915","name":"marubio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=monsterid&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=monsterid&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/464544cdbd75315146f2e2de9fa97073db157c4e2ef80a527d3ccfa975d62fb1?s=96&d=monsterid&r=g","caption":"marubio"},"url":"https:\/\/suport.fundesplai.org\/es\/author\/marubio\/"}]}},"_links":{"self":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/8396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/comments?post=8396"}],"version-history":[{"count":0,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/posts\/8396\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media\/7991"}],"wp:attachment":[{"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/media?parent=8396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/categories?post=8396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/suport.fundesplai.org\/es\/wp-json\/wp\/v2\/tags?post=8396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}